{"id":1811,"date":"2009-02-05T19:17:00","date_gmt":"2009-02-05T19:17:00","guid":{"rendered":""},"modified":"2021-07-26T00:41:01","modified_gmt":"2021-07-26T00:41:01","slug":"los-origenes-de-monte-aguila","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/","title":{"rendered":"Los or\u00edgenes de Monte Aguila"},"content":{"rendered":"<p><a href=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5299395033593285362\" src=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg\" style=\"cursor: pointer; float: left; height: 89px; margin: 0px 10px 10px 0px; width: 143px;\" \/><\/a>La localidad de Monte Aguila, distante unos siete kil\u00f3metros al suroeste de la localidad de Cabrero, provincia de Biob\u00edo, se ha hecho famosa en los \u00faltimos a\u00f1os y su nombre ha sonado a lo largo del pa\u00eds.  Primero fue con \u201cEl Monteaguilino\u201d con su gallina castellana que, hace algunos a\u00f1os, hizo bailar a toda la Quinta Vergara, en el Festival de Vi\u00f1a del mar con la guaracha del \u201cCaballito de Metal\u201d. Aunque su tema no gan\u00f3 y hubo pol\u00e9mica por la condici\u00f3n folcl\u00f3rica del tema, alcanz\u00f3 bastante popularidad que se ha mantenido a la fecha.  En los \u00faltimos a\u00f1os, otro vecino de la localidad ha brillado con luces propias. Luis Cavar\u00eda, ex &#8211; jugador de Deportes Concepci\u00f3n que actualmente milita en la Universidad de Chile, a quien los cronistas deportivos del diario El Mercurio han catalogado como \u201cel monteaguilino m\u00e1s famoso de Chile\u201d.&nbsp;<\/p>\n<div><\/div>\n<div>Pero la historia de esta localidad, siete kil\u00f3metros al sur de Cabrero, tiene or\u00edgenes m\u00e1s bien recientes.  De hecho, seg\u00fan el historiador Tito Figueroa en su libro \u201cCabrero, una aproximaci\u00f3n hist\u00f3rica\u201d, el sector donde actualmente se ubica el pueblo de Monte \u00c1guila estaba en el distrito del mismo nombre de la subdelegaci\u00f3n de Yumbel, pero sin evidencias que existiera un poblado a comienzos del siglo XX.  En el texto de Solano Astaburuaga publicado el 1899, donde se describe detalladamente el Departamento de Rere, menciona pueblos, caser\u00edos y lugares, s\u00f3lo aparece el fundo Monte de \u00c1guila.&nbsp;<\/div>\n<div><\/div>\n<div>A partir del censo de 1907, sostiene Figueroa, puede tenerse una estad\u00edstica demogr\u00e1fica oficial para el poblado, contando en ese entonces con 91 habitantes.   Sin duda, el Ferrocarril del Sur, la construcci\u00f3n del Transandino (que recuera al \u201cCaballito de Metal\u201d) y el aumento de la productividad de las haciendas de la zona dieron vida a este n\u00facleo urbano ubicado a 466 km de Santiago, a 7 km al sur de Cabrero y a 115 m s.n.m.4.  Prueba de lo anterior fue su acelerado crecimiento poblacional, llegando en la d\u00e9cada del 30 casi a mil000 habitantes y duplic\u00e1ndose 30 a\u00f1os m\u00e1s tarde. Seg\u00fan el censo de 1992, cuenta con 5 mil 207 habitantes.   Para el historiador, referirse a Monte \u00c1guila \u201ces recordar el antiguo ramal que part\u00eda desde la estaci\u00f3n del pueblo hasta Polcura, recorriendo 72 km de paradero en paradero y de pueblo en pueblo\u201d.&nbsp;<\/div>\n<div><\/div>\n<div>Un paseante de hace tres d\u00e9cadas recuerda que \u00abcuando conoc\u00ed (Monte Aguila)hace m\u00e1s de 30 a\u00f1os formaba un tren mixto de pasajeros, carga y animales, arrastrado por una peque\u00f1a locomotora a vapor, que empleaba le\u00f1a. Ocurr\u00eda que cerca de la estaci\u00f3n de Campanario y frente a los fundos Tres Ranchos y Primavera Sur, la caldera perd\u00eda presi\u00f3n y el tren se deten\u00eda. Entonces los pasajeros ten\u00edan que bajarse a buscar cuanto palo encontraban para poder alimentarla y seguir el viaje\u00bb.   Sin duda muchos recordar\u00e1n con nostalgia este ramal, que conectaba el interior cordillerano con los grandes centros poblados y que dej\u00f3 de rodar a principios de la d\u00e9cada del 80. Igual que otros de la zona, van quedando lentamente en el olvido, pero siempre tras ellos una historia por contar.&nbsp;<\/div>\n<div><\/div>\n<div>Tambi\u00e9n asociada a Monte \u00c1guila est\u00e1 la Cooperativa El\u00e9ctrica Charr\u00faa (Coelcha), abastecida por Endesa, a trav\u00e9s de la subestaci\u00f3n de Charr\u00faa. Tuvo sus inicios en una sesi\u00f3n de la Municipalidad de Yumbel, el 19 de mayo de 1946. Luego las tres municipalidades del Departamento de Yumbel iniciaron un vasto plan de electrificaci\u00f3n que permiti\u00f3 dotar con la energ\u00eda necesaria a pueblos y fundos, dando un impulso decisivo al desarrollo de la zona.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La localidad de Monte Aguila, distante unos siete kil\u00f3metros al suroeste de la localidad de Cabrero, provincia de Biob\u00edo, se ha hecho famosa en los \u00faltimos a\u00f1os y su nombre ha sonado a lo largo del pa\u00eds. Primero fue con \u201cEl Monteaguilino\u201d con su gallina castellana que, hace algunos a\u00f1os, hizo bailar a toda la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[],"class_list":["post-1811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cabrero","category-historia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los or\u00edgenes de Monte Aguila - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los or\u00edgenes de Monte Aguila - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"La localidad de Monte Aguila, distante unos siete kil\u00f3metros al suroeste de la localidad de Cabrero, provincia de Biob\u00edo, se ha hecho famosa en los \u00faltimos a\u00f1os y su nombre ha sonado a lo largo del pa\u00eds. Primero fue con \u201cEl Monteaguilino\u201d con su gallina castellana que, hace algunos a\u00f1os, hizo bailar a toda la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-05T19:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T00:41:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"143\" \/>\n\t<meta property=\"og:image:height\" content=\"89\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los or\u00edgenes de Monte Aguila\",\"datePublished\":\"2009-02-05T19:17:00+00:00\",\"dateModified\":\"2021-07-26T00:41:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/\"},\"wordCount\":637,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/plaza_monteaguila1.jpg\",\"articleSection\":[\"Cabrero\",\"Historia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/\",\"name\":\"Los or\u00edgenes de Monte Aguila - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/plaza_monteaguila1.jpg\",\"datePublished\":\"2009-02-05T19:17:00+00:00\",\"dateModified\":\"2021-07-26T00:41:01+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/plaza_monteaguila1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/plaza_monteaguila1.jpg\",\"width\":143,\"height\":89},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/los-origenes-de-monte-aguila\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los or\u00edgenes de Monte Aguila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los or\u00edgenes de Monte Aguila - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/","og_locale":"es_ES","og_type":"article","og_title":"Los or\u00edgenes de Monte Aguila - Nuestro Bio B\u00edo","og_description":"La localidad de Monte Aguila, distante unos siete kil\u00f3metros al suroeste de la localidad de Cabrero, provincia de Biob\u00edo, se ha hecho famosa en los \u00faltimos a\u00f1os y su nombre ha sonado a lo largo del pa\u00eds. Primero fue con \u201cEl Monteaguilino\u201d con su gallina castellana que, hace algunos a\u00f1os, hizo bailar a toda la [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-02-05T19:17:00+00:00","article_modified_time":"2021-07-26T00:41:01+00:00","og_image":[{"width":143,"height":89,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/"},"author":{"name":"","@id":""},"headline":"Los or\u00edgenes de Monte Aguila","datePublished":"2009-02-05T19:17:00+00:00","dateModified":"2021-07-26T00:41:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/"},"wordCount":637,"commentCount":2,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg","articleSection":["Cabrero","Historia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/","url":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/","name":"Los or\u00edgenes de Monte Aguila - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg","datePublished":"2009-02-05T19:17:00+00:00","dateModified":"2021-07-26T00:41:01+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#primaryimage","url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg","contentUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/plaza_monteaguila1.jpg","width":143,"height":89},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/los-origenes-de-monte-aguila\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Los or\u00edgenes de Monte Aguila"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/1811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=1811"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/1811\/revisions"}],"predecessor-version":[{"id":1852,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/1811\/revisions\/1852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media\/1851"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=1811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=1811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=1811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}