{"id":2659,"date":"2009-02-02T19:46:00","date_gmt":"2009-02-02T19:46:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/02\/02\/ranquil-y-lonquimay\/"},"modified":"2022-09-13T11:52:33","modified_gmt":"2022-09-13T11:52:33","slug":"ranquil-y-lonquimay","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/","title":{"rendered":"Ranquil y Lonquimay"},"content":{"rendered":"<p><a href=\"http:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/SYdN4X-VrXI\/AAAAAAAAGZs\/_1lWZfmVqqQ\/s1600-h\/ranquil31.jpg\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5298289117528173938\" style=\"cursor: pointer; float: left; height: 89px; margin: 0px 10px 10px 0px; width: 143px;\" src=\"http:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/SYdN4X-VrXI\/AAAAAAAAGZs\/_1lWZfmVqqQ\/s200\/ranquil31.jpg\" alt=\"\" border=\"0\" \/><\/a>Grove, Allende y Barreto. La lucha contra el nacismo y las milicias republicanas de la oligarqu\u00eda, hizo vestir de uniforme a los socialistas. Arriba, Grove, m\u00e1ximo lider socialista, despu\u00e9s de la repentina muerte de Matte, en 1934, habla en un acto p\u00fablico. A su lado, la imagen del joven m\u00e9dico y dirigente del partido en Valpara\u00edso, Salvador Allende, que seis a\u00f1os despu\u00e9s seria Ministro de Salubridad del Presidente Aguirre Cerda. Abajo, el primer m\u00e1rtir del socialismo, H\u00e9ctor Barreto, muerto en un enfrentamiento con los nazis del MNS.<\/p>\n<div><\/div>\n<div>La situaci\u00f3n que se vive a nivel mundial, a partir de la Gran Depresi\u00f3n, y que se extiende por los primeros a\u00f1os de la d\u00e9cada 1930, es de particular inestabilidad, debido a que se trata de la m\u00e1s profunda crisis econ\u00f3mica capitalista. En la Uni\u00f3n Sovi\u00e9tica, Joseph Stalin impone su dictadura personal, desvirtuando la revoluci\u00f3n de octubre y las aspiraciones de la clase obrera, en funci\u00f3n de los objetivos del Estado. Se empiezan a aplicar los planes quinquenales, que privilegian la construcci\u00f3n de una Patria Sovi\u00e9tica, por sobre la internacionalizaci\u00f3n revolucionaria propuesta por el trotskismo.<\/div>\n<div><\/div>\n<div>En la pugna de poder Trotsky debe huir de la Uni\u00f3n Sovi\u00e9tica, exili\u00e1ndose en M\u00e9xico, mientras sus partidarios son brutalmente reprimidos. En Estados Unidos asume Franklin D. Roosevelt, con su pol\u00edtica del New Deal, que robustece la funci\u00f3n del Estado, a fin de superar la grave crisis econ\u00f3mica y social, lo cual, repercutir\u00e1 en todo el mundo, especialmente en Am\u00e9rica Latina. Alemania, en tanto, luego del quiebre de la Bolsa en Wall Street, qued\u00f3 pr\u00e1cticamente en la ruina, debiendo cerrar varios bancos. Millones de obreros quedaron cesantes, mientras comenzaban a surgir un movimiento pol\u00edtico nacionalista y militarista, encabezado por Hitler.<\/div>\n<div><\/div>\n<div>El Partido Nazi, en 1930, obten\u00eda 107 esca\u00f1os en el Reichtang (parlamento), transform\u00e1ndose en la segunda fuerza pol\u00edtica del pa\u00eds, ante las debilidades del movimiento socialista, enfrentado entre la tendencia socialdem\u00f3crata y la revolucionaria. En enero de 1933, Adolf Hitler asume como Jefe de Gobierno, apoyado por su partido, por los militares y los magnates industriales. El nazismo y el militarismo comienzan a esparcirse como mancha de aceite por Francia, Rumania, Austria, Espa\u00f1a, Portugal, Estados Unidos, los Balcanes, y, por supuesto, Chile. En Italia, ya gobernaba el fascismo, encabezado por Benito Mussolini, surgido en el enfrentamiento con los socialistas.<\/div>\n<div><\/div>\n<div>Am\u00e9rica Latina es sacudida por una serie de golpes de Estado, surgiendo caudillos militares, que, echando mano al cuartelazo, se imponen sobre las sociedades sacudidas por la crisis. Una gran cantidad de exiliados se refugian en Chile, gran parte de los cuales, se vinculan al Partido Socialista. Entre ellos estuvieron refugiados varios l\u00edderes del APRA (Acci\u00f3n Popular Revolucionaria Americanista), fundado por Ra\u00fal Haya de la Torre. Los apristas influenciaron notablemente a los dirigentes socialistas chilenos, especialmente a Grove y Schnacke, que asumieron el planteamiento latinoamericanista enarbolado por aquellos. En tanto, en Nicaragua, un l\u00edder revolucionario daba la lucha contra la intervenci\u00f3n norteamericana y su t\u00edtere Anastasio Somoza. Se trataba del general C\u00e9sar Augusto Sandino, que combat\u00eda en las monta\u00f1as de Las Segovias, desde la batalla de J\u00edcaro, en 1926, frente a un pu\u00f1ado de hombres. Morir\u00eda, en 1934, fusilado en el promontorio de La Calavera, cerca de Managua, junto a dos de sus oficiales. En 1932, es fundado en Chile, el Movimiento Nacional Socialista (MNS), por miembros de la colonia alemana y personas de la peque\u00f1a burgues\u00eda. Postulando un Estado portaliano, ataca al liberalismo y a los socialistas. Pronto publican la revista \u00abAcci\u00f3n Chilena\u00bb, sobresaliendo Carlos Keller, como su te\u00f3rico, y Jorge Gonz\u00e1lez Von Marees, como su caudillo. Haciendo uso de los resquicios de la ley que hab\u00eda permitido la creaci\u00f3n de las Milicias Republicanas, crearon las Tropas Nacionalistas de Asalto (TNA), cuerpos de choque callejero, que actuaron fundamentalmente contra los socialistas y comunistas, ante la impasibilidad del gobierno. Ante aquellos ataques, los socialistas se vieron obligados a formar sus propias fuerzas de choque, surgiendo las Milicias Socialistas, que disputaron las calles a las TNA. En esos enfrentamientos cayeron destacados j\u00f3venes socialistas.<\/div>\n<div><\/div>\n<div>En Concepci\u00f3n, morir\u00eda Manuel Bast\u00edas, dirigente de la Federaci\u00f3n Juvenil Socialista (FJS). En La Cisterna, muere Julio Llanos. Pero, el caso m\u00e1s relevante, es la muerte de H\u00e9ctor Barreto, joven poeta, miembro de la FJS, que es baleado por los nazis en la intersecci\u00f3n de la calle San Diego con Avenida Matta, en diciembre de 1936. Sin embargo, las escaramuzas tambi\u00e9n se producen entre socialistas y comunistas, provocando el debilitamiento del movimiento obrero. Del seno del Partido Conservador, por aquella \u00e9poca, surge una nueva generaci\u00f3n de dirigentes juveniles, vinculados al movimiento de la Acci\u00f3n Cat\u00f3lica, que comienzan a desarrollar las ideas socialcristianas, y que dan vida, inicialmente, a la Falange Conservadora, que pasar\u00e1 a denominarse, posteriormente, Falange Nacional. Entre ellos sobresalen Bernardo Leighton, Radomiro Tomic y Eduardo Frei. Chile, luego de los dif\u00edciles primeros a\u00f1os de esa d\u00e9cada, consolida su r\u00e9gimen institucional, previa derrota del militarismo.<\/div>\n<div><\/div>\n<div>La alianza del gobierno de Alessandri, con las clases poseedoras, permite resolver la crisis. Haciendo uso de las facultades extraordinarias que le entregara el parlamento, Alessandri constituy\u00f3 por decreto las Milicias Republicanas, cuerpo armado civil que depend\u00eda exclusivamente del Presidente de la Rep\u00fablica, que constituy\u00f3 el necesario equilibrio para aplacar las opciones militaristas dentro de las Fuerzas Armadas. El hombre fuerte de su gobierno fue Gustavo Ross Santamar\u00eda, Ministro de Hacienda, conocido magnate azucarero y especulador burs\u00e1til, quien logr\u00f3 normalizar la situaci\u00f3n econ\u00f3mica. Ricardo Donoso lo define como un hombre sin escr\u00fapulos morales ni jur\u00eddicos, ajeno a la cultura general m\u00e1s elemental, formado en la escuela de las especulaciones burs\u00e1tiles, pero, movido por una ambici\u00f3n sin freno.<\/div>\n<div><\/div>\n<div>Grandes negociados escandalizaron la vida econ\u00f3mica nacional, teniendo como protagonista al Ministro de Hacienda. Uno de ellos fue el de la Compa\u00f1\u00eda de Electricidad, empresa de capitales extranjeros, que sac\u00f3 100 millones de pesos del pa\u00eds, burlando la ley de cambios. Denunciado el hecho a la justicia, la Corte Suprema impuso a la compa\u00f1\u00eda una multa de 55 millones de pesos, la que nunca fue pagada, ya que el Ministro de Hacienda levant\u00f3 la sanci\u00f3n, sin dar explicaci\u00f3n alguna. Otro esc\u00e1ndalo fue la disoluci\u00f3n de la COSACH (Corporaci\u00f3n del Salitre de Chile), entidad repudiada por el pa\u00eds, siendo sustituida por la Corporaci\u00f3n de Ventas del Salitre y Yodo, que entreg\u00f3 el 75% de sus utilidades a los consorcios extranjeros para el pago de bonos adeudados. Entre 1936 y 1937, se vendi\u00f3 salitre por 12,1 millones de d\u00f3lares, de los cuales el fisco chileno s\u00f3lo recibi\u00f3 3 millones. \u00c9stos negociados se llevaron a cabo en el contexto de una pol\u00edtica econ\u00f3mica antipopular, ejercida a trav\u00e9s de una devaluaci\u00f3n monetaria permanente, y de una inflaci\u00f3n que afectaba directamente los presupuestos de las familias proletarias. Esto generaba constantes movimientos de protestas, que eran violentamente reprimidas por el gobierno.<\/div>\n<div><\/div>\n<div>La tasa de mortalidad bordeaba el 25%. En 1937, 12.155 personas murieron de tuberculosis. M\u00e1s de 400.000 nulos estaban al margen de la educaci\u00f3n. La propiedad de la tierra se divid\u00eda de la siguiente forma: el latifundio, constituido por el 2% de los propietarios, pose\u00eda el 78% de las tierras; la propiedad media, que representaba al 16% de los propietarios, pose\u00eda el 18%; en tanto, el minifundio, que constitu\u00eda el 82% de los propietarios, s\u00f3lo pose\u00eda el 4% de la tierra. Considerando la tierra cultivable, el 68% de ella estaba en manos de un 0,9% de los propietarios. Una encuesta realizada en 1936, entre 12.000 familias de inquilinos \u2013 campesinos con goce de vivienda en los latifundios -, se\u00f1alaba que el 99% de esas familias com\u00eda carne s\u00f3lo una vez al mes, que un 97% no ten\u00edan accesos a leche y que el 76% viv\u00eda en ranchos inhabitables. \u00c9stos factores incid\u00edan en el progresivo despoblamiento de los campos y en la migraci\u00f3n hacia los centros urbanos, aumentando la disponibilidad de mano de obra proletaria.<\/div>\n<div><\/div>\n<div>En aquel panorama, se escribir\u00e1 uno de los hechos m\u00e1s amargos de las luchas del campesinado chileno: la sangrienta represi\u00f3n en Ranquil y Lonquimay, un bald\u00f3n perenne para el segundo gobierno de Arturo Alessandri. Tales sucesos tuvieron lugar en los aleda\u00f1os cordilleranos de Malleco, donde nacen los r\u00edos que forman el majestuoso Bio B\u00edo, en una zona ubicada entre las sierras de Pemehue, Nevada y Velluda, donde los campesinos de origen ind\u00edgena hab\u00edan sido arrinconados en tierras que nadie ambicionaba por su esterilidad. Era una zona agreste, de pobres lavaderos de oro, callej\u00f3n de contrabandistas de ganado argentino. La tierra un poco m\u00e1s cultivable hab\u00eda sido arrebatada a los ind\u00edgenas, a fines del siglo XIX, y repartida en hijuelas a colonos pobres, quienes las cultivaron por a\u00f1os. La tierra mejor, hab\u00eda quedado para los nuevos latifundistas que surgieron a fines del siglo XIX y principios del siglo XX. Cientos de familias campesinas se formaron en torno a aquellos terru\u00f1os g\u00e9lidos, de lluvias eternas, sin regularizar sus t\u00edtulos de propiedad.<\/div>\n<div><\/div>\n<div>El Estado chileno, pese a que hab\u00eda hecho las asignaciones, nunca se preocup\u00f3 de regularizar los t\u00edtulos de propiedad, y los campesinos no ten\u00edan dinero para pagar abogados y tr\u00e1mites legales. Vivieron en las pobres hijuelas, compartiendo con los ind\u00edgenas las privaciones y las necesidades. All\u00ed nacieron sus hijos, se criaron y formaron nuevos hogares. Sin embargo, a principios de 1936, un terrateniente present\u00f3 una reclamaci\u00f3n en Nitrito, exigiendo una orden de desalojo de los campesinos que ocupaban lo que \u00e9l reivindicaba como su propiedad. Comprendiendo \u00e9stos que no ten\u00edan asidero legal, pese a que llevaban all\u00ed m\u00e1s de una generaci\u00f3n, propusieron a las autoridades que el gobierno cancelara el valor de esas tierras al reclamante, y ellos, a su vez, pagar\u00edan por ellas en un plazo prudente. Sin embargo, mientras aquellas tratativas se desarrollaban, los carabineros comenzaron a hostigar a los campesinos, contra los cuales ten\u00edan especial encono, por considerarlos c\u00f3mplices del contrabando de la zona.<\/div>\n<div><\/div>\n<div>Utilizando contra los hijueleros todos los abusos y medios de atemorizamiento posibles, la polic\u00eda fue creando una sensaci\u00f3n de injusticia entre los campesinos, que abon\u00f3 los esp\u00edritus de rebeld\u00eda. No quiso el terrateniente vender sus tierras, si el gobierno se preocup\u00f3 de darles una soluci\u00f3n. Mientras, los carabineros volv\u00edan a advertir que deb\u00edan abandonar las tierras. Cuando las tierras estaban reci\u00e9n labradas, y comenzaba el crudo invierno del sur chileno, lleg\u00f3 la fuerza policial a desalojarlos, destruyendo los cercos e incendiando los ranchos, expuls\u00e1ndolos sin misericordia, y conduci\u00e9ndolos hasta terrenos est\u00e9riles, m\u00e1s arriba de la misma precordillera, sin alimentos, sin habitaci\u00f3n. El sentimiento de odio incubado hacia las autoridades, comenz\u00f3 a materializarse, as\u00ed como la certeza de que aquella injusticia no pod\u00eda quedar sin castigo. En Nitrito, Ranquil, Quilleime, Lolco y Trubul, los campesinos se unieron en defensa de los expulsados, recibiendo tambi\u00e9n el apoyo de los mapuches de la reducci\u00f3n Maripe. Avanzado ya el invierno, en junio de 1936, la desesperaci\u00f3n, el hambre, el fr\u00edo y el odio, dieron paso a la revuelta. Varios miles de campesinos, armados de viejos fusiles y escopetas, asaltaron las pulper\u00edas y bodegas de los latifundios cercanos, y asumieron posiciones de enfrentamiento. El desarrollo de las ideas socialistas en Chile. Por Sebasti\u00e1n Jans<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Grove, Allende y Barreto. La lucha contra el nacismo y las milicias republicanas de la oligarqu\u00eda, hizo vestir de uniforme a los socialistas. Arriba, Grove, m\u00e1ximo lider socialista, despu\u00e9s de la repentina muerte de Matte, en 1934, habla en un acto p\u00fablico. A su lado, la imagen del joven m\u00e9dico y dirigente del partido en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12327,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,10],"tags":[],"class_list":["post-2659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alto-bio-bio","category-historia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ranquil y Lonquimay - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ranquil y Lonquimay - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Grove, Allende y Barreto. La lucha contra el nacismo y las milicias republicanas de la oligarqu\u00eda, hizo vestir de uniforme a los socialistas. Arriba, Grove, m\u00e1ximo lider socialista, despu\u00e9s de la repentina muerte de Matte, en 1934, habla en un acto p\u00fablico. A su lado, la imagen del joven m\u00e9dico y dirigente del partido en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-02T19:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-13T11:52:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/Ranquil-y-Lonquimay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"143\" \/>\n\t<meta property=\"og:image:height\" content=\"89\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ranquil y Lonquimay\",\"datePublished\":\"2009-02-02T19:46:00+00:00\",\"dateModified\":\"2022-09-13T11:52:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/\"},\"wordCount\":1966,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/Ranquil-y-Lonquimay.jpg\",\"articleSection\":[\"Alto Bio B\u00edo\",\"Historia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/\",\"name\":\"Ranquil y Lonquimay - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/Ranquil-y-Lonquimay.jpg\",\"datePublished\":\"2009-02-02T19:46:00+00:00\",\"dateModified\":\"2022-09-13T11:52:33+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/Ranquil-y-Lonquimay.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/Ranquil-y-Lonquimay.jpg\",\"width\":143,\"height\":89},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ranquil-y-lonquimay\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ranquil y Lonquimay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ranquil y Lonquimay - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/","og_locale":"es_ES","og_type":"article","og_title":"Ranquil y Lonquimay - Nuestro Bio B\u00edo","og_description":"Grove, Allende y Barreto. La lucha contra el nacismo y las milicias republicanas de la oligarqu\u00eda, hizo vestir de uniforme a los socialistas. Arriba, Grove, m\u00e1ximo lider socialista, despu\u00e9s de la repentina muerte de Matte, en 1934, habla en un acto p\u00fablico. A su lado, la imagen del joven m\u00e9dico y dirigente del partido en [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-02-02T19:46:00+00:00","article_modified_time":"2022-09-13T11:52:33+00:00","og_image":[{"width":143,"height":89,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/Ranquil-y-Lonquimay.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/"},"author":{"name":"","@id":""},"headline":"Ranquil y Lonquimay","datePublished":"2009-02-02T19:46:00+00:00","dateModified":"2022-09-13T11:52:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/"},"wordCount":1966,"commentCount":1,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/Ranquil-y-Lonquimay.jpg","articleSection":["Alto Bio B\u00edo","Historia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/","url":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/","name":"Ranquil y Lonquimay - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/Ranquil-y-Lonquimay.jpg","datePublished":"2009-02-02T19:46:00+00:00","dateModified":"2022-09-13T11:52:33+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#primaryimage","url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/Ranquil-y-Lonquimay.jpg","contentUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/Ranquil-y-Lonquimay.jpg","width":143,"height":89},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/ranquil-y-lonquimay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Ranquil y Lonquimay"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/2659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=2659"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/2659\/revisions"}],"predecessor-version":[{"id":12328,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/2659\/revisions\/12328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media\/12327"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=2659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=2659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=2659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}