{"id":3158,"date":"2009-02-05T23:49:00","date_gmt":"2009-02-05T23:49:00","guid":{"rendered":""},"modified":"2021-08-02T02:52:41","modified_gmt":"2021-08-02T02:52:41","slug":"fuerte-de-nacimiento","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/","title":{"rendered":"Fuerte de Nacimiento"},"content":{"rendered":"<p><a href=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5299464886321881922\" src=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg\" style=\"cursor: pointer; float: left; height: 89px; margin: 0px 10px 10px 0px; width: 143px;\" \/><\/a>La ciudad de Nacimiento se ubica en un pe\u00f1\u00f3n de la cordillera de Nahuelbuta y tiene un origen militar, pues su formaci\u00f3n se remonta a la creaci\u00f3n de la Plaza Fuerte de Nacimiento durante la Colonia.  Desde las primeras d\u00e9cadas de conquista, los espa\u00f1oles intentaron ejercer su dominio sobre los nuevos territorio. La continua lucha con los mapuches oblig\u00f3 al espa\u00f1ol a crear un espacio fronterizo, as\u00ed se estableci\u00f3 el r\u00edo Biob\u00edo como frontera entre los mundos hispano e ind\u00edgena. Para defender el territorio, la Corona adopt\u00f3 diversas medidas y la construcci\u00f3n de fuertes en lugares estrat\u00e9gicos fue una de ellas.  Los fuertes fueron asentamientos militares en el territorio de la Araucan\u00eda, cuya funci\u00f3n era ejercer soberan\u00eda, dominio y protecci\u00f3n.&nbsp;<\/p>\n<div><\/div>\n<div>Para cumplir eficientemente su objetivo, deb\u00edan tener algunos requisitos fundamentales: su emplazamiento ten\u00eda que estar en lugares elevados para poseer un dominio visual del espacio circundante, y para asegurar la defensa se buscaban sitios que dificultaran o frenaran el ataque mapuche, ten\u00edan que estar al borde de v\u00edas naturales para asegurar las comunicaciones y, finalmente, deb\u00edan ser lugares que suministraran agua, alimentos y materiales de construcci\u00f3n.   Sus formas generalmente eran cuadradas o triangulares y para su construcci\u00f3n se utiliz\u00f3 madera y piedras.&nbsp;<\/div>\n<div><\/div>\n<div>Aunque, si bien es cierto, se utilizaron excelentes t\u00e9cnicas constructivas, muy pocas fortificaciones se conservaron debido a las continuas destrucciones de los fuertes por parte de los mapuches, a la erosi\u00f3n, las condiciones clim\u00e1ticas, los temblores, incendios y el transcurso del tiempo.  En la ribera norte del r\u00edo Bio B\u00edo y cerca de la confluencia con el r\u00edo Vergara, el 24 de diciembre de 1603 el Gobernador del Reino, Alonso de Ribera, funda el fuerte con el nombre de Nacimiento, en memoria del nacimiento de Jesucristo, y lo deja con una guarnici\u00f3n de 100 soldados al mando de don Alonso Gonz\u00e1lez de N\u00e1jera.&nbsp;<\/div>\n<div><\/div>\n<div>En 1613 fue totalmente destruido y llevado a la l\u00ednea misma del r\u00edo Bio B\u00edo, atacado repetidamente por los nativos fue sucesivamente destruido y reconstruido en 1665, 1724 y 1739.   Finalmente fue trasladado a la parte sur del Bio B\u00edo, al poniente del r\u00edo Vergara y a 1 km. de la junta de ambos cursos fluviales. Su favorable emplazamiento, a orillas de un r\u00edo navegable y sobre una barranca muy empinada que le daba gran dominio del territorio, movi\u00f3 al Mariscal de Campo y Gobernador del Reino, don Manuel de Amat y Juniet, a otorgarle, en diciembre de 1756, el t\u00edtulo de villa con la intenci\u00f3n de fortificar la frontera y congregar a la poblaci\u00f3n que se encontraba dispersa en la zona.&nbsp;<\/div>\n<div><\/div>\n<div>El concepto de Plaza Fuerte fue desarrollado en el siglo XVIII y, como su nombre lo indica, cumpl\u00eda una funci\u00f3n militar defensiva y a su vez, de resguardo de la villa fundada al exterior del fuerte. El Gobernador Amat en persona se encarg\u00f3 del dise\u00f1o y supervisi\u00f3n de la obra. Hizo delinear la villa y sus defensas dividiendo el terreno en 10 manzanas y mand\u00f3 levantar el nuevo castillo fortificado.&nbsp;<\/div>\n<div><\/div>\n<div>El fuerte se levant\u00f3 en el extremo oriente de la ciudad sobre una escarpada que enfrenta al r\u00edo Vergara. La planta, con forma de trapecio, era t\u00edpica del siglo XVIII. Originalmente el edificio estuvo separado del pueblo por un foso. La poblaci\u00f3n se encontraba distribuida en tres calles convergentes al Castillo y rodeada de gruesas murallas de cinco metros de altura, construidas en alba\u00f1iler\u00eda y argamasa de cal. En el dise\u00f1o original cuatro baluartes en forma de tri\u00e1ngulo se proyectaban en las cuatro esquinas del fuerte, fuera de la l\u00ednea de las murallas exteriores; pero modificaciones posteriores alteraron los baluartes de los \u00e1ngulos suroriente y norponiente.&nbsp;<\/div>\n<div><\/div>\n<div>Es importante se\u00f1alar que, adem\u00e1s de las funciones se\u00f1aladas, el fuerte de Nacimiento cumpli\u00f3 un importante rol en la interacci\u00f3n entre ind\u00edgenas y espa\u00f1oles, en lo que hoy llamamos relaciones fronterizas. Los fuertes ejercieron una importante funci\u00f3n de comercio, en tiempos de paz se produc\u00eda un intercambio espont\u00e1neo de productos, gener\u00e1ndose un considerable tr\u00e1fico de mercanc\u00edas. Durante el siglo XVIII, la Plaza Fuerte de Nacimiento fue un destacado punto de comercio.  La importancia militar que el Fuerte de Nacimiento tuvo durante la Colonia se prolong\u00f3 durante gran parte del siglo XIX. En las luchas por la independencia fue muy disputado; en 1813 cay\u00f3 en manos de los realistas y en 1817 fue recuperado por el Mariscal Alc\u00e1zar. Antes que comenzaran las campa\u00f1as de Pacificaci\u00f3n de la Araucan\u00eda, Nacimiento debi\u00f3 sufrir el asedio de los ind\u00edgenas en 1860, 1861 y 1862.&nbsp;<\/div>\n<div><\/div>\n<div>A partir de 1865, junto con Los Angeles y Angol, se constituy\u00f3 en una de las principales bases de operaci\u00f3n de la llamada campa\u00f1a de pacificaci\u00f3n de las tierras situadas entre el r\u00edo Bio B\u00edo y Valdivia. En 1875 Nacimiento recibi\u00f3 el t\u00edtulo de ciudad.  En los \u00faltimos a\u00f1os del siglo XIX el fuerte fue desguarnecido y su artiller\u00eda fue retirada. Nacimiento perdi\u00f3 su importancia de enclave militar con el desplazamiento de la frontera hacia el sur. El tiempo y el abandono causaron gran deterioro en el fuerte y con el terremoto de 1920 perdi\u00f3, finalmente, sus rasgos originales; el foso se convirti\u00f3 en la calle Lastra y la explanada fue transformada en Plaza P\u00fablica.&nbsp;<\/div>\n<div><\/div>\n<div>En 1921 y 1940 se construyeron escaleras en la muralla oriente. Despu\u00e9s del terremoto de 1939, la comisar\u00eda de carabineros se traslad\u00f3 al fuerte y lo reconstruy\u00f3, all\u00ed ocupan un antiguo Cuartel de Polic\u00edas comunales, sucesores de las Guardias C\u00edvicas.  El paisaje que rodea al fuerte es de gran belleza y entre las caudalosas aguas del r\u00edo Vergara se observan extensos campos y antiguas tierras mapuches.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad de Nacimiento se ubica en un pe\u00f1\u00f3n de la cordillera de Nahuelbuta y tiene un origen militar, pues su formaci\u00f3n se remonta a la creaci\u00f3n de la Plaza Fuerte de Nacimiento durante la Colonia. Desde las primeras d\u00e9cadas de conquista, los espa\u00f1oles intentaron ejercer su dominio sobre los nuevos territorio. La continua lucha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3182,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,10,26,75],"tags":[],"class_list":["post-3158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fuertes-espanoles","category-historia","category-monumentos","category-nacimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fuerte de Nacimiento - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fuerte de Nacimiento - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"La ciudad de Nacimiento se ubica en un pe\u00f1\u00f3n de la cordillera de Nahuelbuta y tiene un origen militar, pues su formaci\u00f3n se remonta a la creaci\u00f3n de la Plaza Fuerte de Nacimiento durante la Colonia. Desde las primeras d\u00e9cadas de conquista, los espa\u00f1oles intentaron ejercer su dominio sobre los nuevos territorio. La continua lucha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-05T23:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-02T02:52:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"143\" \/>\n\t<meta property=\"og:image:height\" content=\"89\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fuerte de Nacimiento\",\"datePublished\":\"2009-02-05T23:49:00+00:00\",\"dateModified\":\"2021-08-02T02:52:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/\"},\"wordCount\":997,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/fuerte_vista_lateral1.jpg\",\"articleSection\":[\"Fuertes Espa\u00f1oles\",\"Historia\",\"Monumentos\",\"Nacimiento\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/\",\"name\":\"Fuerte de Nacimiento - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/fuerte_vista_lateral1.jpg\",\"datePublished\":\"2009-02-05T23:49:00+00:00\",\"dateModified\":\"2021-08-02T02:52:41+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/fuerte_vista_lateral1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/fuerte_vista_lateral1.jpg\",\"width\":143,\"height\":89},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/fuerte-de-nacimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fuerte de Nacimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fuerte de Nacimiento - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Fuerte de Nacimiento - Nuestro Bio B\u00edo","og_description":"La ciudad de Nacimiento se ubica en un pe\u00f1\u00f3n de la cordillera de Nahuelbuta y tiene un origen militar, pues su formaci\u00f3n se remonta a la creaci\u00f3n de la Plaza Fuerte de Nacimiento durante la Colonia. Desde las primeras d\u00e9cadas de conquista, los espa\u00f1oles intentaron ejercer su dominio sobre los nuevos territorio. La continua lucha [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-02-05T23:49:00+00:00","article_modified_time":"2021-08-02T02:52:41+00:00","og_image":[{"width":143,"height":89,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/"},"author":{"name":"","@id":""},"headline":"Fuerte de Nacimiento","datePublished":"2009-02-05T23:49:00+00:00","dateModified":"2021-08-02T02:52:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/"},"wordCount":997,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg","articleSection":["Fuertes Espa\u00f1oles","Historia","Monumentos","Nacimiento"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/","url":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/","name":"Fuerte de Nacimiento - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg","datePublished":"2009-02-05T23:49:00+00:00","dateModified":"2021-08-02T02:52:41+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#primaryimage","url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg","contentUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2009\/02\/fuerte_vista_lateral1.jpg","width":143,"height":89},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/fuerte-de-nacimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Fuerte de Nacimiento"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/3158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=3158"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/3158\/revisions"}],"predecessor-version":[{"id":3183,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/3158\/revisions\/3183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media\/3182"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=3158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=3158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=3158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}