{"id":4499,"date":"2009-11-23T23:08:00","date_gmt":"2009-11-23T23:08:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/11\/23\/cuento-bizcocho-banado-relleno-con-manjar\/"},"modified":"2009-11-23T23:08:00","modified_gmt":"2009-11-23T23:08:00","slug":"cuento-bizcocho-banado-relleno-con-manjar","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/","title":{"rendered":"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar"},"content":{"rendered":"<div style=\"text-align: justify;\">Hab\u00eda que juntar las moneditas de 5 y de 10, reservarse a veces el chocolatito o las pastillas del vuelto para poder acumular m\u00e1s pesos -en esos tiempos cuando te agachabas por recoger $5-. Pasaban d\u00edas, una semana o dos tal vez, porque no pod\u00eda comprar uno, deb\u00eda recolectar para dos y as\u00ed llevarle a mi hermana tambi\u00e9n. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Costaban $100, pero su precio significaba los vueltos del pan o las moneditas que \u201csobraban\u201d del pasaje, a pesar, que nada sobraba. Cuando una iba al negocio a \u201ccomprarse un rico\u201d, como si las frutas o la comida de mam\u00e1 no fueran ricas, y el almac\u00e9n de la esquina quedaba muy, muy lejos. el mundo era tan gigante y mis pasos avanzaban tan poco.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Se consegu\u00edan a escondidas, creyendo que la mam\u00e1 no sab\u00eda, cuando se iba por el pan reservado a la Se\u00f1ora Rosa y me pon\u00eda de puntillas para dejar muchas moneditas calientes sobre el mes\u00f3n. \u2013i kero doh cokman-. Los que se guardaban en los bolsillos y no dentro de la bolsa de g\u00e9nero, para salir corriendo hasta la pieza y llegar donde mi hermana, cerrar la puerta: \u2013te kompr\u00e9 un riko-.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Entonces, se abr\u00eda el paquete con cuidado, se dejaba extendido el papel y empez\u00e1bamos por los bordes, donde el chocolate estaba m\u00e1s duro. Luego el chocolate en las capas de arriba y de abajo, hab\u00eda que despegarlo prolijamente, si no, se desarmaba. Cuando el pastel se ve\u00eda blanco con una raya caf\u00e9 horizontal, se tomaban con mucha delicadeza, separando los bizcochos del manjar, los que ya estaban medios molidos y picados. Despu\u00e9s, lentamente, se dejaba derretir el manjar, una masa blanda que se pod\u00eda estirar, en la lengua. Finalizando con pasarle el dedo al envoltorio o los dientes, cuando se derret\u00eda, y as\u00ed aprovecharlo todo.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">No s\u00e9 si es porque he probado m\u00e1s sabores o porque los qu\u00edmicos eran menos antes, y de mejor calidad, o porque me esforzaba por conseguir un chocman, que sab\u00edan m\u00e1s sabrosos que ahora. Pero es que ayer me compr\u00e9 uno y se le cayeron f\u00e1cilmente los bordes y record\u00e9 que los chocman, para nosotras, nunca se probaron enteros, siempre por partes, entonces, al comerlos \u2013un procedimiento que duraba alrededor de 15 minutos, cuando los minutos eran m\u00e1s largos- hab\u00eda que abrir el paquete con cuidado, dejar extendido el papel y empezar por los bordes, donde el chocolate estaba m\u00e1s duro\u2026<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Por Yenny Burgos<br \/>Palabras A Lo Largo De Tu Pelo<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Lea M\u00e1s en<\/span>: <a href=\"http:\/\/palabrasalolargodetupelo.blogspot.com\/\">http:\/\/palabrasalolargodetupelo.blogspot.com\/<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hab\u00eda que juntar las moneditas de 5 y de 10, reservarse a veces el chocolatito o las pastillas del vuelto para poder acumular m\u00e1s pesos -en esos tiempos cuando te agachabas por recoger $5-. Pasaban d\u00edas, una semana o dos tal vez, porque no pod\u00eda comprar uno, deb\u00eda recolectar para dos y as\u00ed llevarle a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[217],"tags":[],"class_list":["post-4499","post","type-post","status-publish","format-standard","hentry","category-cuentos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Hab\u00eda que juntar las moneditas de 5 y de 10, reservarse a veces el chocolatito o las pastillas del vuelto para poder acumular m\u00e1s pesos -en esos tiempos cuando te agachabas por recoger $5-. Pasaban d\u00edas, una semana o dos tal vez, porque no pod\u00eda comprar uno, deb\u00eda recolectar para dos y as\u00ed llevarle a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-23T23:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar\",\"datePublished\":\"2009-11-23T23:08:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/\"},\"wordCount\":448,\"commentCount\":0,\"articleSection\":[\"Cuentos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/\",\"name\":\"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2009-11-23T23:08:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/cuento-bizcocho-banado-relleno-con-manjar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/","og_locale":"es_ES","og_type":"article","og_title":"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar - Nuestro Bio B\u00edo","og_description":"Hab\u00eda que juntar las moneditas de 5 y de 10, reservarse a veces el chocolatito o las pastillas del vuelto para poder acumular m\u00e1s pesos -en esos tiempos cuando te agachabas por recoger $5-. Pasaban d\u00edas, una semana o dos tal vez, porque no pod\u00eda comprar uno, deb\u00eda recolectar para dos y as\u00ed llevarle a [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-11-23T23:08:00+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/"},"author":{"name":"","@id":""},"headline":"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar","datePublished":"2009-11-23T23:08:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/"},"wordCount":448,"commentCount":0,"articleSection":["Cuentos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/","url":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/","name":"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2009-11-23T23:08:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/cuento-bizcocho-banado-relleno-con-manjar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"CUENTO: Bizcocho Ba\u00f1ado Relleno Con Manjar"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=4499"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4499\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=4499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=4499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=4499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}