{"id":4634,"date":"2009-10-03T00:05:00","date_gmt":"2009-10-03T00:05:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/10\/03\/la-leyenda-de-la-laguna-de-trupan\/"},"modified":"2009-10-03T00:05:00","modified_gmt":"2009-10-03T00:05:00","slug":"la-leyenda-de-la-laguna-de-trupan","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/","title":{"rendered":"La Leyenda de la Laguna De Trup\u00e1n"},"content":{"rendered":"<div style=\"text-align: justify;\">De acuerdo a la recopilaci\u00f3n de leyendas en la biblioteca p\u00fablica de Hu\u00e9pil, en la comuna de Tucapel, existe una curiosa leyenda que explica el origen de la laguna de Trup\u00e1n, situada en la localidad del mismo nombre, en plenos faldeos cordilleranos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Seg\u00fan este relato, en ese lugar no hab\u00eda ning\u00fan cuerpo de agua. Sin embargo, hace muchos a\u00f1os, cuando unos mapuches jugaban a la chueca o pal\u00edn en el mismo lugar hubo una gran pelea donde muri\u00f3 el hijo del lonco.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Por eso, \u00e9ste maldijo la cancha para que nadie pudiera jugar en ese lugar.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Fue as\u00ed que cuando el grupo de iba del lugar, a uno de los mapuches presentes le dieron ganas de orinar. Fue tanto lo que hizo que en el mismo lugar se form\u00f3 la laguna Trup\u00e1n, impidiendo el uso deportivo de esa parte, tal como lo hab\u00eda afirmado el indignado jefe ind\u00edgena.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">As\u00ed se asegura en el relato, en las noches de luna llena se escucha c\u00f3mo orina el mapuche. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo a la recopilaci\u00f3n de leyendas en la biblioteca p\u00fablica de Hu\u00e9pil, en la comuna de Tucapel, existe una curiosa leyenda que explica el origen de la laguna de Trup\u00e1n, situada en la localidad del mismo nombre, en plenos faldeos cordilleranos. Seg\u00fan este relato, en ese lugar no hab\u00eda ning\u00fan cuerpo de agua. Sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,108],"tags":[],"class_list":["post-4634","post","type-post","status-publish","format-standard","hentry","category-mitos-y-leyendas","category-tucapel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Leyenda de la Laguna De Trup\u00e1n - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Leyenda de la Laguna De Trup\u00e1n - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"De acuerdo a la recopilaci\u00f3n de leyendas en la biblioteca p\u00fablica de Hu\u00e9pil, en la comuna de Tucapel, existe una curiosa leyenda que explica el origen de la laguna de Trup\u00e1n, situada en la localidad del mismo nombre, en plenos faldeos cordilleranos. Seg\u00fan este relato, en ese lugar no hab\u00eda ning\u00fan cuerpo de agua. Sin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-03T00:05:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Leyenda de la Laguna De Trup\u00e1n\",\"datePublished\":\"2009-10-03T00:05:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/\"},\"wordCount\":187,\"commentCount\":0,\"articleSection\":[\"Mitos y Leyendas\",\"Tucapel\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/\",\"name\":\"La Leyenda de la Laguna De Trup\u00e1n - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2009-10-03T00:05:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-leyenda-de-la-laguna-de-trupan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Leyenda de la Laguna De Trup\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Leyenda de la Laguna De Trup\u00e1n - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/","og_locale":"es_ES","og_type":"article","og_title":"La Leyenda de la Laguna De Trup\u00e1n - Nuestro Bio B\u00edo","og_description":"De acuerdo a la recopilaci\u00f3n de leyendas en la biblioteca p\u00fablica de Hu\u00e9pil, en la comuna de Tucapel, existe una curiosa leyenda que explica el origen de la laguna de Trup\u00e1n, situada en la localidad del mismo nombre, en plenos faldeos cordilleranos. Seg\u00fan este relato, en ese lugar no hab\u00eda ning\u00fan cuerpo de agua. Sin [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-10-03T00:05:00+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/"},"author":{"name":"","@id":""},"headline":"La Leyenda de la Laguna De Trup\u00e1n","datePublished":"2009-10-03T00:05:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/"},"wordCount":187,"commentCount":0,"articleSection":["Mitos y Leyendas","Tucapel"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/","url":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/","name":"La Leyenda de la Laguna De Trup\u00e1n - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2009-10-03T00:05:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-leyenda-de-la-laguna-de-trupan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"La Leyenda de la Laguna De Trup\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=4634"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4634\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=4634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=4634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=4634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}