{"id":4701,"date":"2009-09-09T21:33:00","date_gmt":"2009-09-09T21:33:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/09\/09\/septiembre-mes-de-la-patria\/"},"modified":"2009-09-09T21:33:00","modified_gmt":"2009-09-09T21:33:00","slug":"septiembre-mes-de-la-patria","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/","title":{"rendered":"Septiembre: Mes De La Patria"},"content":{"rendered":"<div style=\"text-align: justify;\">Esquinazos de Cueca simult\u00e1neos a nivel nacional y coros al un\u00edsono entonando nuestro Himno en todo el pa\u00eds, son algunos de los hitos preparados para celebrar el mes de Fiestas Patrias.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Las actividades Bicentenario de este mes no pudieron tener un mejor comienzo que el concierto sinf\u00f3nico que ofreci\u00f3 nuestra Orquesta Juvenil Bicentenario, la cual deslumbr\u00f3 a todo un pa\u00eds interpretando al un\u00edsono el Himno Nacional, al igual que otras 14 Orquestas Bicentenario por todo el pa\u00eds.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">De esta forma, el mes de las Fiestas Patrias viene cargado de iniciativas, concursos y premios Bicentenario. El objetivo es que los chilenos y chilenas se hagan parte de este momento y celebraci\u00f3n hist\u00f3rica, a trav\u00e9s de las actividades y las diferentes \u00e1reas de inter\u00e9s desarrolladas con miras a celebrar los 200 a\u00f1os de vida independiente.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Calendario Actividades, Premios Y Concursos Septiembre<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Del 2 de septiembre al 2 de noviembre<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">\u201cZoom Gente Chile 2010\u201d<\/span><\/div>\n<div style=\"text-align: justify;\">El objetivo es crear un registro gr\u00e1fico que permita revelar c\u00f3mo nos vemos a nosotros mismos, retratando a la gente de Chile a trav\u00e9s de im\u00e1genes que reflejen nuestra realidad e identidad. Pueden participar profesionales y aficionados de la fotograf\u00eda, sin restricci\u00f3n de edad o nacionalidad con s\u00f3lo una obra por autor. T\u00e9cnica libre. Se puede participar hasta el 2 de noviembre de 2009. Bases en www.chilebicentenario.cl<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">16 de septiembre, 11.30 horas<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Restauraci\u00f3n de la Bandera de la Jura de la Independencia<\/span><\/div>\n<div style=\"text-align: justify;\">El proyecto de Restauraci\u00f3n de la Bandera de la Jura de la Independencia se trat\u00f3 de un proceso complejo y de largo desarrollo, que se realiz\u00f3 con especial acuciosidad. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La idea no es que la bandera sobre la que se jur\u00f3 la Independencia de Chile, el 12 de febrero de 1818, quede como nueva, sino que recupere sus colores e integridad, pero con el respeto a su origen y su valor hist\u00f3rico, como \u00fanico testimonio que ha perdurado de la \u00e9poca en que Chile se consolid\u00f3 como naci\u00f3n independiente.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La bandera ya restaurada ser\u00e1 exhibida en el Museo Hist\u00f3rico Nacional a partir del 17 de septiembre de 2009.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">17 de septiembre 12:00<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">\u201cEsquinazo a la patria\u201d<\/span><\/div>\n<div style=\"text-align: justify;\">Consiste en un esquinazo de cueca simult\u00e1neo a nivel nacional. En Concepci\u00f3n este esquinazo se realizar\u00e1 el 17 de septiembre, a las 12:00 horas, en la Plaza de la Independencia de la ciudad.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Esta actividad pretende generar una serie de 15 encuentros por toda la regi\u00f3n, en los cuales podr\u00e1 participar cualquier pareja de ciudadanos que exponga la cueca local en su sentido m\u00e1s popular, aut\u00e9ntico y cotidiano. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La convocatoria para esta actividad esta abierta y esta siendo recibida a trav\u00e9s de formularios electr\u00f3nicos por los encargados de cultura en cada Municipalidad. Es importante se\u00f1alar que El Gran Esquinazo no es un concurso, se trata de una muestra y un encuentro en el cual la ciudadan\u00eda  expondr\u00e1 los diferentes tipos de cueca existentes en Chile y adem\u00e1s de resaltar la importancia, vitalidad y diversidad de nuestro baile nacional. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">17 de septiembre 20:00 horas<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Gala Bicentenario<\/span><\/div>\n<div style=\"text-align: justify;\">Segundo Concierto de la Orquesta Bicentenario. Formada por 86 integrantes seleccionados de las 31 orquestas juveniles existentes en la zona. La conformaci\u00f3n de las Orquestas Bicentenario es parte del programa \u201cOrquesta Juveniles Uniendo a Chile\u201d creado por la Comisi\u00f3n Bicentenario en conjunto con la Fundaci\u00f3n de Orquestas Juveniles e Infantiles. La meta del proyecto es crear una sinf\u00f3nica juvenil en cada regi\u00f3n del pa\u00eds, conformada por ni\u00f1os y ni\u00f1as entre 10 y 16 a\u00f1os, brindando as\u00ed nuevas oportunidades para el desarrollo musical de los j\u00f3venes.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Se realizar\u00e1 en el Teatro de la Universidad de Concepci\u00f3n, el jueves 17 de septiembre a las 20:00 horas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">17 de septiembre, horario por definir<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Chile pinta su cara (CHILE PINTA)<\/span><\/div>\n<div style=\"text-align: justify;\">La campa\u00f1a de car\u00e1cter nacional, denominada \u201cChile pinta su cara\u201d -que ser\u00e1 lanzada el 17 de septiembre de 2009 y que culminar\u00e1 en septiembre de 2010- est\u00e1 inspirada en la antigua tradici\u00f3n de pintar las fachadas con motivo de las Fiestas Patrias. Es una invitaci\u00f3n a las personas, autoridades y a toda la comunidad a embellecer casas, plazas y espacios p\u00fablicos de cada comuna, con motivo del Bicentenario.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">17 de septiembre, 12.00 horas<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Pa\u00f1uelos al viento<\/span><\/div>\n<div style=\"text-align: justify;\">Un baile ciudadano protagonizado por 500 parejas ser\u00e1 parte del acto central que se realizar\u00e1 el pr\u00f3ximo 17 de septiembre en la Plaza de la Constituci\u00f3n y que llevar\u00e1 por nombre \u201cPa\u00f1uelos al Viento\u201d.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Dicho evento viene a culminar el programa \u201cEsquinazo a la Patria\u201d, iniciativa Bicentenario que incluye la selecci\u00f3n de 15 parejas cuequeras (una por cada regi\u00f3n), que ser\u00e1n las encargadas de exponer el baile nacional en su sentido m\u00e1s popular, aut\u00e9ntico y cotidiano. Ser\u00e1 una fiesta que incorporar\u00e1 toda la gran diversidad de modos y peculiaridades que adquiere la cueca en cada uno de los rincones de Chile.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">17 de septiembre, 19.00 horas<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Evento \u201cY se arm\u00f3 la fiesta del Bicentenario\u201d<\/span><\/div>\n<div style=\"text-align: justify;\">Organizado por el Consejo de la Cultura y las Artes, con el apoyo de la Comisi\u00f3n Bicentenario, el 17 de septiembre se realizar\u00e1 la primera celebraci\u00f3n esperando la  partida Oficial del Bicentenario de nuestra Rep\u00fablica de Chile, que hemos titulado \u00a1Y se arm\u00f3 la Fiesta Bicentenario!<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ser\u00e1 una fiesta para celebrar, para sumar y no restar, con artistas de todas las tendencias pol\u00edticas, sociales y religiosas, unidos por un solo coraz\u00f3n: el coraz\u00f3n de Chile.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">23 de septiembre, horario por definir<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Lanzamiento Concurso \u201cEl Quiltro del Bicentenario\u201d<\/span><\/div>\n<div style=\"text-align: justify;\">Concurso que convoca a todos los chilenos y extranjeros residentes en el pa\u00eds a participar con una fotograf\u00eda de un \u201cperro quiltro\u201d Se debe adjuntar a la fotograf\u00eda una breve descripci\u00f3n del animal y por qu\u00e9 debiera ser el ganador. Si el animal ha sido acogido en una casa, se debe indicar el nombre que se le puso y si se trata de un perro de la calle, se le debe asignar uno.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Los tres primeros lugares recibir\u00e1n c\u00e1maras fotogr\u00e1ficas de \u00faltimo modelo.<\/div>\n<div style=\"text-align: justify;\">Las postulaciones estar\u00e1n abiertas hasta el 23 de noviembre.<\/div>\n<div style=\"text-align: justify;\">Ver Bases en www.chilebicentenario.cl<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">26 de septiembre, 12.00 horas<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Voces para el Bicentenario<\/span><\/div>\n<div style=\"text-align: justify;\">Al 21 de agosto m\u00e1s de 14 mil chilenos ya se hab\u00edan inscrito para participar en el proyecto \u201cVoces para el Bicentenario\u201d, iniciativa que se llevar\u00e1 a cabo el pr\u00f3ximo 26 de septiembre, como una forma de rendir homenaje a la celebraci\u00f3n de los 200 a\u00f1os de Chile. Ese mediod\u00eda, coros de todo el pa\u00eds se reunir\u00e1n en plazas, teatros, iglesias, calles y glorietas con la comunidad para interpretar en forma simult\u00e1nea el Himno Nacional seguido de un repertorio definido por cada coro. La invitaci\u00f3n es para todo tipo de agrupaciones corales, ya sean profesionales o aficionadas.<\/div>\n<div style=\"text-align: justify;\">M\u00e1s del 50% de las comunas de Chile ya ha confirmado su participaci\u00f3n.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">27 de septiembre, 12.00 horas.<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Festival de volantines<\/span><\/div>\n<div style=\"text-align: justify;\">Para finalizar el mes de la patria, el \u00faltimo domingo de este mes, en el Parque O\u2019Higgins, se realizar\u00e1 una actividad recreativa en la que se repartir\u00e1n gratuitamente m\u00e1s de 4 mil volantines de diversos colores con la imagen oficial del Bicentenario. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">28 de septiembre, primer sorteo de premios entre los votantes<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">El Cancionero del Bicentenario \u201cLas 200 canciones m\u00e1s queridas por los chilenos\u201d <\/span><\/div>\n<div style=\"text-align: justify;\">El objetivo de esta iniciativa es descubrir las 200 canciones m\u00e1s queridas por los chilenos. La idea es que sea una radiograf\u00eda de las preferencias musicales de los chilenos en el marco del Bicentenario. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">No se busca la mejor canci\u00f3n, sino la que m\u00e1s gusta, ya sea nacional o internacional. <\/div>\n<div style=\"text-align: justify;\">Mediante el sistema de 1 RUT &#8211; un voto, cada chileno puede inscribir una \u00fanica canci\u00f3n de su preferencia en un formulario que encontrar\u00e1 en www.chilebicentenario.cl\/cancionero.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Junto con prorrogar el concurso hasta el pr\u00f3ximo a\u00f1o, se abri\u00f3 la participaci\u00f3n a todos sin restricci\u00f3n de edad.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Entre todas las personas que participen de este concurso, se sortear\u00e1n 4 premios de $100.000 pesos cada uno, y 5 giftcards de $20.000 pesos, gentileza de Feria Mix. El primer sorteo de premios entre los votantes ser\u00e1 el 28 de septiembre (2 premios de $100.000 y 5 giftcards de $20.000). <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Convoca Comisi\u00f3n Bicentenario<\/div>\n<div style=\"text-align: justify;\">Ver Bases en www.chilebicentenario.cl<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Hasta el 30 de septiembre<\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">\u201cEnfoca Chile 2010\u201d<\/span><\/div>\n<div style=\"text-align: justify;\">Concurso de fotograf\u00eda que invita a todos los chilenos, extranjeros, ni\u00f1os, adultos, ya sean profesionales o aficionados, a tomarle una fotograf\u00eda al Chile del Bicentenario. El concurso, busca que la comunidad refleje a trav\u00e9s de la fotograf\u00eda, como medio masivo de expresi\u00f3n, su impresi\u00f3n particular sobre las modificaciones que est\u00e1n viviendo las ciudades de Chile con miras al Bicentenario de la Rep\u00fablica de Chile. <\/div>\n<div style=\"text-align: justify;\">Ver Bases en chilebicentenario.cl<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esquinazos de Cueca simult\u00e1neos a nivel nacional y coros al un\u00edsono entonando nuestro Himno en todo el pa\u00eds, son algunos de los hitos preparados para celebrar el mes de Fiestas Patrias. Las actividades Bicentenario de este mes no pudieron tener un mejor comienzo que el concierto sinf\u00f3nico que ofreci\u00f3 nuestra Orquesta Juvenil Bicentenario, la cual [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-4701","post","type-post","status-publish","format-standard","hentry","category-eventos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Septiembre: Mes De La Patria - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Septiembre: Mes De La Patria - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Esquinazos de Cueca simult\u00e1neos a nivel nacional y coros al un\u00edsono entonando nuestro Himno en todo el pa\u00eds, son algunos de los hitos preparados para celebrar el mes de Fiestas Patrias. Las actividades Bicentenario de este mes no pudieron tener un mejor comienzo que el concierto sinf\u00f3nico que ofreci\u00f3 nuestra Orquesta Juvenil Bicentenario, la cual [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-09T21:33:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Septiembre: Mes De La Patria\",\"datePublished\":\"2009-09-09T21:33:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/\"},\"wordCount\":1463,\"commentCount\":0,\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/\",\"name\":\"Septiembre: Mes De La Patria - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2009-09-09T21:33:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/septiembre-mes-de-la-patria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Septiembre: Mes De La Patria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Septiembre: Mes De La Patria - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/","og_locale":"es_ES","og_type":"article","og_title":"Septiembre: Mes De La Patria - Nuestro Bio B\u00edo","og_description":"Esquinazos de Cueca simult\u00e1neos a nivel nacional y coros al un\u00edsono entonando nuestro Himno en todo el pa\u00eds, son algunos de los hitos preparados para celebrar el mes de Fiestas Patrias. Las actividades Bicentenario de este mes no pudieron tener un mejor comienzo que el concierto sinf\u00f3nico que ofreci\u00f3 nuestra Orquesta Juvenil Bicentenario, la cual [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-09-09T21:33:00+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/"},"author":{"name":"","@id":""},"headline":"Septiembre: Mes De La Patria","datePublished":"2009-09-09T21:33:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/"},"wordCount":1463,"commentCount":0,"articleSection":["Eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/","url":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/","name":"Septiembre: Mes De La Patria - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2009-09-09T21:33:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/septiembre-mes-de-la-patria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Septiembre: Mes De La Patria"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=4701"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4701\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=4701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=4701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=4701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}