{"id":4835,"date":"2009-07-17T15:58:00","date_gmt":"2009-07-17T15:58:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/07\/17\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/"},"modified":"2009-07-17T15:58:00","modified_gmt":"2009-07-17T15:58:00","slug":"la-marginalidad-del-escritora-por-ingrid-odgers-toloza","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/","title":{"rendered":"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza"},"content":{"rendered":"<div style=\"text-align: justify;\">Tema profundo y extenso el de la marginalidad, quiero primeramente apuntar que habr\u00eda sido un aporte a estas actividades literarias, tratar como tema aparte, el de la marginaci\u00f3n de la mujer en la literatura chilena especialmente la regional. Por lo corto del tiempo respecto a ello mencionar\u00e9 lo siguiente en forma bastante sucinta:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Hubo \u00e9poca en nuestras letras nacionales en que las mujeres ten\u00edan literalmente vedada su participaci\u00f3n. Era patrimonio masculino. Una consecuencia natural del machismo imperante, sin duda alguna, machismo que, por felicidad, se ha batido en derrota y permite la entrada de la mujer en las arenas literarias.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A modo de an\u00e9cdota, digamos que en \u201cin illo tempore\u201d se dec\u00eda que la pluma era para usarla, por parte de las mujeres, &#8230; en los sombreros femeninos, no en la escritura.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Las cosas han cambiado favorablemente y las mujeres han ingresado con propiedad y talento en la galer\u00eda de la literatura chilena.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">A modo de pre\u00e1mbulo y s\u00f3lo con el \u00e1nimo de informar, mencionaremos las escritoras que han hecho camino al andar en esto de publicar libros y dar a conocer su visi\u00f3n de la vida. Posteriormente, centraremos nuestra atenci\u00f3n, en forma muy breve, por supuesto, sobre la importancia que tuvo en la historia literaria, a nuestro juicio, la obra de tres escritoras de todos conocidos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Los panoramas e historias literarias le dan a Mercedes Mar\u00edn Del Solar el honroso t\u00edtulo de la primera mujer escritora. Con posterioridad surgen en el estrado Mariana Cox (Shade), Marta Jara, Marta Brunet, Magdalena Petit, Gabriela Mistral, Carmen Abalos, Isidora Aguirre, Margarita Aguirre, Rosa Cruchaga, Winett de Rokha, Delia Dominguez, In\u00e9s Echverr\u00eda (Iris), Isabel Velasco, Carmen Gaete Nieto, Mar\u00eda Carolina Geel,, Mar\u00eda Elena Gertner, Ana Mar\u00eda Guiraldes, Ester Huneus (Marcela Paz), Emma Jauch, Amanda Labarca, Matilde Ladr\u00f3n de Guevara, Mar\u00eda Cristina Menares, Mar\u00eda Monvel, Alicia Morel, Violeta Parra, Violeta Quevedo, Chela Reyes, Elisa Serrano, Mar\u00eda Silva Ossa, Pepita Turina, Mercedes Valdivieso, Marta Vergara, Magdalena Vial, Sara Vial, Teresa Wilms, Mar\u00eda Flora Ya\u00f1ez, Mar\u00eda Elvira Piwonka, Olga Acevedo, Isabel Velasco, etc.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Hemos nombrado tanto a prosistas como a poetas o poetisas de cierto renombre, como una forma de rendir homenaje a las mujeres que emplearon muy bien la pluma&#8230; con la mano.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En la actualidad, se nota un creciente n\u00famero de mujeres, de todas las edades, que incursionan en la poem\u00e1tica y en la narrativa con singular \u00e9xito y calidad, abriendo amplias perspectivas para su desarrollo literario. A modo de informaci\u00f3n, nombramos algunas escritoras que pertenecen a la nueva generaci\u00f3n, compar\u00e1ndolas con las anteriormente citadas: Elena Castedo, Isabel Allende, Luc\u00eda Guerra, Alejandra Basualto, Jacqueline Bacells, Cecilia Beuchat, Ana Mar\u00eda del R\u00edo, Diamela Eltit, Marcela Serrano, P\u00eda Barros, Sonia Gonzalez, Lilian Elphick, Andrea Maturana, Heddy Navarro, Paz Molina, Astrid Fugellie, Rossana Byrne, Elvira Hern\u00e1ndez, Teresa Calder\u00f3n, Isabel G\u00f3mez, Rosabetty Mu\u00f1oz, etc.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Existe un gran n\u00famero. \u00bfCu\u00e1nto m\u00e1s en las regiones de Chile?<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">S\u00f3lo tres mujeres han obtenido el Premio Nacional de Literatura: Gabriela Mistral (poes\u00eda), Marta Brunet y Marcela Paz (narrativa).<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Predominio masculino sin duda. Que da para hablar sobre la Marginaci\u00f3n de la mujer en la Literatura chilena.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Nota: Art\u00edculo a\u00f1o 2007<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Pepita Turina manifest\u00f3 en una ocasi\u00f3n:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En la enciclopedia las mujeres sobresalientes son f\u00e1ciles de contar, mientras que los hombres, para qu\u00e9 descorazonarse. Nuestras condiciones no son para enciclopedias. A s\u00f3lo a TRES escritoras se les ha concedido el Premio nacional de literatura. Si muchas m\u00e1s lo merecen, injusticia, notoria inferioridad en n\u00famero. En todos los pa\u00edses del orbe sucede lo mismo. Sucede con los premios nacionales e internacionales. En la suma de las categor\u00edas del N\u00f3bel lo han recibido cientos de hombres y poqu\u00edsimas mujeres. Quiz\u00e1s unas cuantas creyeron que en 1975, A\u00f1o Internacional de la Mujer, alguna se har\u00eda acreedora a ese galard\u00f3n. No fue as\u00ed.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ellos gobiernan con sus atributos varoniles, ladrones del universo femenino del que se han apoderado dejando a las mujeres el fastidioso dominio del hogar, de la intuici\u00f3n (la raz\u00f3n es masculina), de la frivolidad y del sentimentalismo. Los grandes y bellos amores son privativos de los caballeros, al igual que la composici\u00f3n musical, el arte a gran nivel, la filosof\u00eda, la cirug\u00eda-arte y miles de otras acrobacias parecidas, donde los \u00fanicos que pueden saltar alto y piruetear son los seres humanos de sexo masculino.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Nada irrita m\u00e1s a las escritoras, en general, que o\u00edr este juicio: \u201cescribe como mujer\u201d, ya que eso significa que escribe mal, porque cuando se considera que lo hace bien se dice: \u201cescribe como hombre\u201d. Que se diga escribe como hombre para significar que se tiene fuerza y valor literario es objetable, pero \u201cliteratura femenina\u201d y \u201cliteratura masculina\u201d son clasificaciones HA CONSIDERAR. MultiDi\u00e1logos ES \u201cLETRA\u201d DE MUJER<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">(p\u00e1ginas 123 &#8211; 131)<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00bfQu\u00e9 pasa con la marginaci\u00f3n de las mujeres en la literatura chilena?<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00bfQu\u00e9 pasa con la marginaci\u00f3n de las mujeres en la literatura regional?<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">EN UNA OCASI\u00d3N, Gabriela Mistral dijo:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u201cHay una monta\u00f1a de desprestigio y de rid\u00edculo en Chile echada sobre las mujeres que escribimos\u201d<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">LA MARGINALIDAD<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">1.-QU\u00c9 ES LA MARGINALIDAD<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">2.-MARGINACI\u00d3N SOCIAL<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">3.-MARGINALIDAD EN LA LITERATURA<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">4.-EL ESCRITOR MARGINAL<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">5.-VIVIR AL MARGEN<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">6.-POSIBLES SOLUCIONES-CONCLUSI\u00d3N<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">1.-QU\u00c9 ES LA MARGINALIDAD<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ante esta pregunta, tiendo a pensar que:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La marginalidad es un campo altamente relevante y fecundo, en ella se expresa la po\u00e9tica de la insatisfacci\u00f3n profunda, la incomodidad al olor de las ovejas (ese olor a resignaci\u00f3n tranquilizada del \u201cuno\u201d \u2026porque uno es as\u00ed), en la marginalidad se expresa a su vez, la creatividad de la potencial innovaci\u00f3n o el \u201cg\u00e9rmen\u201d de las revoluciones ciudadanas (nuestros ping\u00fcinos). Algo en com\u00fan tiene la brigada que raya la ciudad, la perseverancia del emprendedor que abre mercados inimaginables, los defensores de los derechos que a\u00fan no son derechos y el artista que provoca al l\u00edmite de conmover o repugnar.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Las voces marginales, son se\u00f1ales, provocaciones que nos muestran nuestros l\u00edmites, nuestros excesos. Es la irreverencia con compromiso. Indignaci\u00f3n e intolerancia a la sensibilidad adormecida por una cotidianeidad anestesiada.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">MARGINACION SOCIAL<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Se entiende por exclusi\u00f3n o marginaci\u00f3n social el proceso por el que una sociedad rechaza a unos determinados individuos, desde la simple indiferencia hasta la represi\u00f3n y reclusi\u00f3n. Tambi\u00e9n se da el caso de quienes, por no concordar con los valores y normas de una determinada sociedad, se automarginan. Caracter\u00edstica com\u00fan a todos los grados y tipos de marginaci\u00f3n es la privaci\u00f3n o dificultad para la normal satisfacci\u00f3n de las necesidades secundarias. Este fen\u00f3meno se puede producir ya sea por seguir los ideales de la comunidad o bien cuando la sociedad responde a los intereses de un grupo minoritario poderoso.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Es interesante mencionar que, como dicho anteriormente, la exclusi\u00f3n social es un proceso, no una condici\u00f3n. Por lo tanto sus fronteras cambian, y qui\u00e9n es excluido o incluido puede variar con el tiempo, dependiendo de la educaci\u00f3n, las caracter\u00edsticas demogr\u00e1ficas, los prejuicios sociales, las pr\u00e1cticas empresariales y las pol\u00edticas p\u00fablicas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">(Inv\u00e1lidos, la tercera edad, los enfermos)<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">MARGINALIDAD Y LITERATURA<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Es sabido que sino se pertenece a un grupo elite, quedamos escribiendo desde la marginalidad. Y esto, lo digo sin gimoteos, tenemos que asumirlo. Con mayor raz\u00f3n si somos mujeres y pertenecemos a regiones.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En el plano de la literatura son las editoriales y las universidades las que marcan las pautas y la cr\u00edtica. Son los que levantan a un escritor como la novedad del momento.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Afortunadamente nosotros sabemos que la literatura se hace por medio de las experiencias de la lectura y por medio del vivir. Un escritor se desarrolla por la lectura, la escritura y la experiencia de vida. Sabemos que un escritor es escritor con taller, sin taller o pese al taller, como manifest\u00f3 un autor mexicano en la Feria de Santiago recientemente. Escribimos, con difusi\u00f3n o sin difusi\u00f3n, el que tiene alma de escritor(a) seguir\u00e1 escribiendo y nutri\u00e9ndose en grupos, a solas, pero no se dar\u00e1 por vencido, persiste en elaborar su obra. Unos, con el prop\u00f3sito de dejar testimonio de su paso por la tierra, otros, con la esperanza de aportar a la literatura, a las nuevas y pr\u00f3ximas generaciones y algunos m\u00e1s o menos por el mero placer de escribir.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">EL ESCRITOR MARGINAL-\u00bfQUI\u00c9N ES?<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Algunos pueden decir que somos marginales pues No seguimos las normas de una sociedad de consumo que envilece con la marca y el estatus socio-econ\u00f3mico.-<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Generalmente cuando se habla de escritores marginales se piensa en:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00b7 -los escritores homosexuales<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00b7 -los escritores franceses o malditos<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00b7 -las escritoras mujeres<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00b7 -los escritores de etnias ind\u00edgenas<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00b7 -los escritores de bajo nivel socio-econ\u00f3mico<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00b7 Los escritores que abordan espacios marginales de las urbes: seg\u00fan estudio de Oscar Galindo de la Universidad Austral, El paseo Ahumada(1983) de Enrique Lihn, Cipango de Tomas Harris, V\u00edrgenes del sol en Cabaret de Alexis Figueroa, Piedras rodantes de Mal\u00fa Urriola, Doble vida de Victor Hugo D\u00edaz, por mencionar algunos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00b7 Para nosotros, los escritores(AS) marginales son aquellos cuyos escritos apenas se conocen \u00f3 se ignoran totalmente. Por lo tanto, cuesta seguirlos, son desconocidos. Pasa con los que pertenecemos a regiones. En mayor medida, eso podemos afirmarlo sin dudar. Pues en Chile, el hecho de pertenecer a una regi\u00f3n y no a la capital tambi\u00e9n nos inserta en la clasificaci\u00f3n de marginales (prescindibles)<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En general, somos los excluidos de la sociedad literaria, la palabra al margen (al borde, en la ribera, al filo), lo se\u00f1ala. Somos los excomulgados del imperio de las letras, dominadas por grupos de poder, editoriales, ministerios, librer\u00edas y universidades. Y no olvidemos considerar a las eternas Vacas sagradas de la literatura, residentes, en su mayor\u00eda, en Santiago, la capital de Chile, que son siempre los m\u00e1s considerados a la hora de mencionar las palabras literatura chilena: tenemos Rojas, Uribe, Parra, Zurita. Que son sombras que siempre acompa\u00f1ar\u00e1n a los escritores emergentes. Por decirlo de alguna manera<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">\u00bfPOR QU\u00c9 SE VIVE FUERA DE LAS NORMAS ESTABLECIDAS?= \u00bfPOR QU\u00c9 SE VIVE AL MARGEN?<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Y \u00bfCu\u00e1les son las normas establecidas existentes en la sociedad y que tiene que observar un escritor?<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Las normas establecidas son leer al escritor m\u00e1s premiado, el m\u00e1s marketeado, al m\u00e1s entrevistado en los diarios, el que tiene el m\u00e1s alto cargo. En el caso de las editoriales publicar a los escritores que m\u00e1s venden. El escritor que vende es el que aparte de tener una obra medianamente buena tiene una pol\u00edtica de marketing, la asesor\u00eda de una empresa de imagen y publicidad. Vende el que tiene cabida en los medios, en la TV en la prensa, etc. Para publicar y vender necesitamos lobby, para ello requerimos dinero. Entonces estamos fuera porque:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">1. Los medios de comunicaci\u00f3n influyen en esta marginaci\u00f3n, no hay apoyo ni consideraci\u00f3n (no hay respeto)<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">2. Las librer\u00edas nos excluyen por no ser publicados en editoriales grandes<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">3. Las universidades no nos contemplan en sus estudios ni actividades mayores o de importancia por no ser graduados en literatura, consideremos adem\u00e1s que ellos tienen un cuerpo docente de literatos. Hacen clases y escriben.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">4. Las bibliotecas no se interesan en nuestros libros. Los reciben y los guardan. Somos escritores sin vitrina.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">5. Las pol\u00edticas de educaci\u00f3n no son suficientes pues no hay incentivo a la lectura. Lo que hay no es suficiente<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">6. La obra del escritor recorre caminos marginales en nuestro pa\u00eds que se dice tierra de poetas, pero carece de lectores que la asuman como un ejercicio cotidiano de comunidad y di\u00e1logo.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">7. No existe la critica-la cr\u00edtica constructiva<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">8. No hay dinero<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">CONCLUSION<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Podr\u00edamos concluir que una parte de la soluci\u00f3n es comprometerse con lo que se crea y no subordinarse, pero tambi\u00e9n podr\u00eda ser de inter\u00e9s reconstruir los c\u00e1nones con los que actualmente se viven por lo que la educaci\u00f3n podr\u00eda tomar parte en esa labor, puesto que es propicia que sea ella quien se encargue no s\u00f3lo de la transmisi\u00f3n de los conocimientos sino tambi\u00e9n de la formaci\u00f3n de car\u00e1cter y que sobretodo ense\u00f1e al sujeto a no ser como un elemento de la producci\u00f3n o como una fuerza de trabajo, sino que se le debe ense\u00f1ar a sentir con todos sus sentidos y a ser coherente con lo que hace y con lo que piensa, puesto que el cuerpo y el alma no deber\u00edan de ser dos elementos aislados sino algo en continua coherencia.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La exclusi\u00f3n social, debida a cualquiera de sus posibles or\u00edgenes, produce siempre en quienes la padecen una p\u00e9rdida o una lesi\u00f3n del disfrute de los derechos fundamentales que como personas les corresponden. La exclusi\u00f3n marca la frontera entre quienes gozan en plenitud de sus derechos y quienes se ven privados de una parte de ellos, con menoscabo de sus capacidades de desarrollo como personas, agravio de su dignidad y, con frecuencia, peligro de su propia vida.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Es claro que toda exclusi\u00f3n es una injusticia. No hay exclusi\u00f3n que pueda proceder del ejercicio de la justicia, cuando lo que produce es el da\u00f1o de la persona, su destrucci\u00f3n f\u00edsica, psicol\u00f3gica o moral. En el caso de los escritores la marginaci\u00f3n, los limita en su realizaci\u00f3n personal, en su realizaci\u00f3n art\u00edstica. Tenemos un ministerio de cultura pero No hay una visi\u00f3n global de lo que existe hoy, en Chile, en literatura. El recurso material, la atenci\u00f3n se centraliza en la capital y en los escritores ya galardonados, reconocidos, gracias a premios, a recursos materiales o pitutos diversos, generalmente pol\u00edticos. Las nuevas reglas de la globalizaci\u00f3n, y los actores que las escriben, se centran en la integraci\u00f3n de los mercados globales, descuidando las necesidades de las personas que los mercados no pueden resolver. El proceso concentra a\u00fan m\u00e1s el poder y acrecienta el n\u00famero de marginales en la sociedad.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">POSIBLES SOLUCIONES<\/span>:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">*Reformas en Educaci\u00f3n, pol\u00edticas culturales, editorial estatal, incrementar la difusi\u00f3n regional&#8212;organizarnos: y eso ha sido imposible.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00bfPodremos alg\u00fan d\u00eda salir del margen? Tal vez no sea lo mejor ser marginales, pero no es tan malo. A\u00fan podemos autoeditar.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Un valor orientador es la opci\u00f3n que el habitante de un pa\u00eds toma ante una disyuntiva: \u00bfescribo o no escribo?, y yo sigo escribiendo, soy escritora, \u201cprefiero este tipo de vida\u201d, porque para m\u00ed, con todo, es la vida \u201cque vale la pena vivir\u201d.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Yo quisiera agregar, antes de finalizar esta exposici\u00f3n, que nosotros mismos como escritores y escritoras marginamos, al no considerar para eventos literarios y culturales, a nuestros pares, por no ser de Santiago, por no tener estudios universitarios en Letras (por no provenir de la Academia) o porque no nos caen bien. Es entonces como sucede lo que el dicho: Pasa que Nadie es profeta en su tierra.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Exposici\u00f3n de Ingrid Odgers en las Jornadas Culturales Centro Cultural de Concepci\u00f3n<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Publicaciones de Ingrid Odgers<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><a href=\"http:\/\/escritoraconcepcion.googlepages.com\/\">http:\/\/escritoraconcepcion.googlepages.com<\/a><\/div>\n<div style=\"text-align: justify;\"><a href=\"http:\/\/ingridodgerstoloza.blogspot.com\/\">http:\/\/ingridodgerstoloza.blogspot.com<\/a><\/div>\n<div style=\"text-align: justify;\"><a href=\"http:\/\/programamundodepoesia.blogspot.com\/\">http:\/\/programamundodepoesia.blogspot.com<\/a><\/div>\n<div style=\"text-align: justify;\"><a href=\"http:\/\/revistalasilla.blogspot.com\/\">http:\/\/revistalasilla.blogspot.com<\/a><\/div>\n<div style=\"text-align: justify;\"><a href=\"http:\/\/biobiogestioncultural.blogspot.com\/\">http:\/\/biobiogestioncultural.blogspot.com<\/a><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tema profundo y extenso el de la marginalidad, quiero primeramente apuntar que habr\u00eda sido un aporte a estas actividades literarias, tratar como tema aparte, el de la marginaci\u00f3n de la mujer en la literatura chilena especialmente la regional. Por lo corto del tiempo respecto a ello mencionar\u00e9 lo siguiente en forma bastante sucinta: Hubo \u00e9poca [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,112],"tags":[],"class_list":["post-4835","post","type-post","status-publish","format-standard","hentry","category-creadores","category-opinion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Marginalidad del Escritor(a), por Ingrid Odgers Toloza - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Tema profundo y extenso el de la marginalidad, quiero primeramente apuntar que habr\u00eda sido un aporte a estas actividades literarias, tratar como tema aparte, el de la marginaci\u00f3n de la mujer en la literatura chilena especialmente la regional. Por lo corto del tiempo respecto a ello mencionar\u00e9 lo siguiente en forma bastante sucinta: Hubo \u00e9poca [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-17T15:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza\",\"datePublished\":\"2009-07-17T15:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/\"},\"wordCount\":2634,\"commentCount\":2,\"articleSection\":[\"Creadores\",\"Opini\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/\",\"name\":\"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2009-07-17T15:58:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/","og_locale":"es_ES","og_type":"article","og_title":"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza - Nuestro Bio B\u00edo","og_description":"Tema profundo y extenso el de la marginalidad, quiero primeramente apuntar que habr\u00eda sido un aporte a estas actividades literarias, tratar como tema aparte, el de la marginaci\u00f3n de la mujer en la literatura chilena especialmente la regional. Por lo corto del tiempo respecto a ello mencionar\u00e9 lo siguiente en forma bastante sucinta: Hubo \u00e9poca [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-07-17T15:58:00+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/"},"author":{"name":"","@id":""},"headline":"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza","datePublished":"2009-07-17T15:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/"},"wordCount":2634,"commentCount":2,"articleSection":["Creadores","Opini\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/","url":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/","name":"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2009-07-17T15:58:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-marginalidad-del-escritora-por-ingrid-odgers-toloza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"La Marginalidad del Escritor(a), por Ingrid Odgers Toloza"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=4835"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4835\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=4835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=4835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=4835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}