{"id":4839,"date":"2009-07-16T00:03:00","date_gmt":"2009-07-16T00:03:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/07\/16\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/"},"modified":"2009-07-16T00:03:00","modified_gmt":"2009-07-16T00:03:00","slug":"jj-vv-de-misque-prepara-la-fiesta-del-chancho","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/","title":{"rendered":"JJ.VV. de Misque Prepara la Fiesta del Chancho"},"content":{"rendered":"<p><a href=\"http:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s1600-h\/fiesta_chancho1.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5358842904187062850\" src=\"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s200\/fiesta_chancho1.jpg\" style=\"float: left; height: 107px; margin: 0px 10px 10px 0px; width: 143px;\" \/><\/a>La comuna estrena nueva fiesta costumbrista, basada en todos los productos que se obtienen del cerdo, desde el costillar, prietas y el pan con chicharrones, todo con el sabor t\u00edpico del campo.<\/p>\n<p>Desde ya los vecinos del sector est\u00e1n trabajando en la primera Fiesta del Chancho que se llevar\u00e1 a cabo el s\u00e1bado 18 y 19 de julio, en el sector de Misque en Yumbel. En la celebraci\u00f3n se podr\u00e1 degustar de todos los platos t\u00edpicos que se producen a partir del chancho: asado, costillar, prietas, longanizas, cocimiento, pan con chicharrones,  y tantas otras cosas con la preparaci\u00f3n t\u00edpica del campo.<\/p>\n<p>Es por ello que desde el domingo est\u00e1n preparando los productos, siguiendo cada paso de lo que exige el Servicio de Salud, Sanidad, y el Municipio. La fiesta en si comenz\u00f3 con la muerte de los 9 chanchos que ofrecer\u00e1 la Junta de vecinos, que tendr\u00e1n uno de los 16 stand que se ubicar\u00e1n en el gran recinto ferial, con una carpa de eventos de 40&#215;20 metros, ubicada en la cancha de f\u00fatbol de la localidad.<\/p>\n<p>La fiesta, adem\u00e1s de la comida tendr\u00e1 actividades recreativas tradicionales, como un campeonato de rayuela, carreras a la chilena, y la t\u00edpica competencia del chancho ensebado. Dentro del recinto ferial habr\u00e1 un show art\u00edstico, en donde conjuntos folcl\u00f3ricos y grupos rancheros amenizar\u00e1n la fiesta.<\/p>\n<p>Todas las actividades, y la entrada al recinto son absolutamente gratuitas, por lo que se convierte en un panorama ideal para toda la familia, a tan s\u00f3lo 12 km. del centro de Yumbel.<\/p>\n<p>Programa 1\u00b0 Fiesta del Chancho en Misque<\/p>\n<p><span style=\"font-weight: bold;\">S\u00e1bado 18 de julio<\/span><\/p>\n<p>9:00 horas. Apertura de Stand.<br \/>12:00 horas. Ceremonia de Inauguraci\u00f3n.<br \/>13:00 horas. Almuerzo, inicio de show Folcl\u00f3rico.<br \/>15:00 horas. Actividades recreativas (Campeonato de Rayuela, Chancho Ensebado).<br \/>15:00 a 18:00 horas. Carreras a la Chilena.<br \/>18:00 horas.  Inicio de Show Art\u00edstico.<br \/>23:00 Horas. Cierre de stands<\/p>\n<p><span style=\"font-weight: bold;\">Domingo 19 de julio<\/span><\/p>\n<p>9:00 horas. Apertura de Stand.<br \/>13:00 horas. Almuerzo, inicio de show Folcl\u00f3rico.<br \/>15:00 horas. Actividades recreativas (Campeonato de Rayuela, Chancho Ensebado).<br \/>15:00 a 18:00 horas. Carreras a la Chilena.<br \/>18:00 horas.  Inicio de Show Art\u00edstico.<br \/>23:00 Horas. Cierre de stands<\/p>\n<p>Programa sujeto a Modificaci\u00f3n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comuna estrena nueva fiesta costumbrista, basada en todos los productos que se obtienen del cerdo, desde el costillar, prietas y el pan con chicharrones, todo con el sabor t\u00edpico del campo. Desde ya los vecinos del sector est\u00e1n trabajando en la primera Fiesta del Chancho que se llevar\u00e1 a cabo el s\u00e1bado 18 y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,109],"tags":[],"class_list":["post-4839","post","type-post","status-publish","format-standard","hentry","category-fiestas-y-tradiciones","category-yumbel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JJ.VV. de Misque Prepara la Fiesta del Chancho - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JJ.VV. de Misque Prepara la Fiesta del Chancho - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"La comuna estrena nueva fiesta costumbrista, basada en todos los productos que se obtienen del cerdo, desde el costillar, prietas y el pan con chicharrones, todo con el sabor t\u00edpico del campo. Desde ya los vecinos del sector est\u00e1n trabajando en la primera Fiesta del Chancho que se llevar\u00e1 a cabo el s\u00e1bado 18 y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-16T00:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s200\/fiesta_chancho1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"JJ.VV. de Misque Prepara la Fiesta del Chancho\",\"datePublished\":\"2009-07-16T00:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/\"},\"wordCount\":368,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/Sl5vOp8xSkI\\\/AAAAAAAALZg\\\/4QkKdkan7OE\\\/s200\\\/fiesta_chancho1.jpg\",\"articleSection\":[\"Fiestas y Tradiciones\",\"Yumbel\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/\",\"name\":\"JJ.VV. de Misque Prepara la Fiesta del Chancho - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/Sl5vOp8xSkI\\\/AAAAAAAALZg\\\/4QkKdkan7OE\\\/s200\\\/fiesta_chancho1.jpg\",\"datePublished\":\"2009-07-16T00:03:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/Sl5vOp8xSkI\\\/AAAAAAAALZg\\\/4QkKdkan7OE\\\/s200\\\/fiesta_chancho1.jpg\",\"contentUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/Sl5vOp8xSkI\\\/AAAAAAAALZg\\\/4QkKdkan7OE\\\/s200\\\/fiesta_chancho1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JJ.VV. de Misque Prepara la Fiesta del Chancho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JJ.VV. de Misque Prepara la Fiesta del Chancho - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/","og_locale":"es_ES","og_type":"article","og_title":"JJ.VV. de Misque Prepara la Fiesta del Chancho - Nuestro Bio B\u00edo","og_description":"La comuna estrena nueva fiesta costumbrista, basada en todos los productos que se obtienen del cerdo, desde el costillar, prietas y el pan con chicharrones, todo con el sabor t\u00edpico del campo. Desde ya los vecinos del sector est\u00e1n trabajando en la primera Fiesta del Chancho que se llevar\u00e1 a cabo el s\u00e1bado 18 y [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-07-16T00:03:00+00:00","og_image":[{"url":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s200\/fiesta_chancho1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/"},"author":{"name":"","@id":""},"headline":"JJ.VV. de Misque Prepara la Fiesta del Chancho","datePublished":"2009-07-16T00:03:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/"},"wordCount":368,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s200\/fiesta_chancho1.jpg","articleSection":["Fiestas y Tradiciones","Yumbel"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/","url":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/","name":"JJ.VV. de Misque Prepara la Fiesta del Chancho - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s200\/fiesta_chancho1.jpg","datePublished":"2009-07-16T00:03:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#primaryimage","url":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s200\/fiesta_chancho1.jpg","contentUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/Sl5vOp8xSkI\/AAAAAAAALZg\/4QkKdkan7OE\/s200\/fiesta_chancho1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/jj-vv-de-misque-prepara-la-fiesta-del-chancho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"JJ.VV. de Misque Prepara la Fiesta del Chancho"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=4839"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4839\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=4839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=4839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=4839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}