{"id":4926,"date":"2009-06-03T05:19:00","date_gmt":"2009-06-03T05:19:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/06\/03\/alicia-pereda-saavedra-palabra-de-mujer\/"},"modified":"2021-09-30T12:43:31","modified_gmt":"2021-09-30T12:43:31","slug":"alicia-pereda-saavedra-palabra-de-mujer","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/","title":{"rendered":"Alicia Pereda Saavedra. Palabra de Mujer"},"content":{"rendered":"<div style=\"text-align: justify;\"><a style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\" href=\"http:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s1600-h\/alicia.bmp\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5342969153770427746\" style=\"float: left; height: 175px; margin: 0px 10px 10px 0px; width: 200px;\" src=\"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s200\/alicia.bmp\" alt=\"\" border=\"0\" \/><\/a>Nac\u00ed en la ciudad de Concepci\u00f3n un 18 de Mayo de 1954. Por razones de trabajo, mis padres fueron trasladados a Yumbel en donde curs\u00e9 mi ense\u00f1anza b\u00e1sica en la Escuela Superior de Ni\u00f1as y en el Liceo Fiscal hasta 1\u00ba Medio terminando mi ense\u00f1anza secundaria en el Liceo de Ni\u00f1as N\u00ba1 en Concepci\u00f3n. Ingres\u00e9 a la carrera de pedagog\u00eda en Biolog\u00eda y Ciencias el a\u00f1o 1972 en la Universidad de Chile sede Antofagasta cursando 3 a\u00f1os.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El amor a los libros fue inculcado por mis padres y desde peque\u00f1a demostr\u00e9 aptitudes para escribir cuentos y poemas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La poes\u00eda es parte fundamental de mi ser, nace como una expresi\u00f3n espont\u00e1nea, sin m\u00e1s recursos que aquellos que me dan las palabras, en ellos plasmo los sentimientos que no son s\u00f3lo m\u00edos sino universales, como el amor y el desamor. La inquietud que siento al ver c\u00f3mo hemos ido destruyendo todo lo hermoso que la sabia naturaleza nos diera.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Mi poes\u00eda nace de esa voz interior que no todos queremos escuchar o que en muchos casos no es o\u00edda cuando revela las injusticias y las desesperanzas. Es simple como el agua de los r\u00edos, como el sue\u00f1o de muchos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Me he desempe\u00f1ado como monitora en el taller literario del Centro Cultural Alaval en la ciudad de Bulnes, donde editamos dos libros.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Represent\u00e9 a la comuna como delegada en los Cabildos Nacionales de Cultura, fui directora, secretaria y presidenta del Taller\u201993 Artes, Letras y Oficios de Bulnes.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Tuve el honor de ser elegida por el escultor Am\u00e9rico Becerra para escribir la ep\u00edgrafe de la escultura El Nuevo Campesino que se levanta en la plaza de Armas de Bulnes.<\/div>\n<div style=\"text-align: justify;\">El a\u00f1o 2008 obtuve el primer lugar en el Festival de todas las Artes V\u00edctor Jara en poes\u00eda.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En mi libro Mariposas en la ci\u00e9naga, prologado por el poeta Lu\u00eds Contreras Jara, dejo plasmada la dualidad que se esconde en lo m\u00e1s profundo del ser humano, es por eso que a veces hablo con la voz de mi dual, en este caso el lado masculino, porque siendo siento que de esta forma mi poes\u00eda expresa lo que no me es permitido decir o sentir, vivir el amor pleno y verme como lo que soy \u201cun aprendiz de ser humano\u201d.<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Y la luz desterrar\u00e1 las sombras\u2026<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Y la luz desterrar\u00e1 las sombras.<\/div>\n<div style=\"text-align: justify;\">Un canto de vida se elevar\u00e1 de las piedras<\/div>\n<div style=\"text-align: justify;\">Esparci\u00e9ndose por quebradas ebrias de sol<\/div>\n<div style=\"text-align: justify;\">Llenando los espacios con dulces ecos<\/div>\n<div style=\"text-align: justify;\">Que repetir\u00e1 el viento entre los \u00e1rboles.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Y la semilla ser\u00e1 fruto jugoso.<\/div>\n<div style=\"text-align: justify;\">Destilando mieles entre los labios v\u00edrgenes<\/div>\n<div style=\"text-align: justify;\">De las morenas v\u00edrgenes de mi pueblo<\/div>\n<div style=\"text-align: justify;\">Que cantan loores a la tierra f\u00e9rtil donde<\/div>\n<div style=\"text-align: justify;\">Crece el trigo que se har\u00e1 pan en su mesa.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Y el cielo se vestir\u00e1 de terciopelo.<\/div>\n<div style=\"text-align: justify;\">Rayos de plata bajar\u00e1n por las quebradas<\/div>\n<div style=\"text-align: justify;\">Hasta besar la sedienta arena del desierto<\/div>\n<div style=\"text-align: justify;\">Para despertarla de su sue\u00f1o milenario<\/div>\n<div style=\"text-align: justify;\">Cuando se borren las fronteras humanas<\/div>\n<div style=\"text-align: justify;\">Y comprenda el hombre que es uno m\u00e1s<\/div>\n<div style=\"text-align: justify;\">En el concierto infinito del universo.<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Cierta vez\u2026<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Cierta vez pregunt\u00e9 al poeta \u00bfqu\u00e9 quieres de m\u00ed?<\/div>\n<div style=\"text-align: justify;\">Si estaba cierto de todo lo que mi alma a\u00f1oraba<\/div>\n<div style=\"text-align: justify;\">Era real en mi vida todo lo escrito y todo lo vivido<\/div>\n<div style=\"text-align: justify;\">Si en cada mirada encontraba los destellos de tus ojos<\/div>\n<div style=\"text-align: justify;\">Y en las risas estaba tu voz despertando las ma\u00f1anas<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Mas el poeta callaba escribiendo en las hojas del agua<\/div>\n<div style=\"text-align: justify;\">Destilando de su pluma gota a gota toda la melancol\u00eda<\/div>\n<div style=\"text-align: justify;\">Fue dejando vac\u00eda mi alma y secos de l\u00e1grimas mis ojos<\/div>\n<div style=\"text-align: justify;\">Al mostrarme los colores que formaban en su poes\u00eda<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00bfQu\u00e9 quieres de m\u00ed? Dije y el poeta alz\u00f3 entonces su voz<\/div>\n<div style=\"text-align: justify;\">Quiero de ti el sabor de los besos que no has dado todav\u00eda<\/div>\n<div style=\"text-align: justify;\">El sollozo de tu boca cuando el amor te arrebata el alma<\/div>\n<div style=\"text-align: justify;\">Aquel temblor de tu cuerpo al recibir los fr\u00e1giles dardos<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Quiero robar ese aroma a jazm\u00edn de tu piel desnuda<\/div>\n<div style=\"text-align: justify;\">Navegar por tus r\u00edos y explora cada uno de sus afluentes<\/div>\n<div style=\"text-align: justify;\">Dormir en el brocal del pozo que encierra tus deseos<\/div>\n<div style=\"text-align: justify;\">Y extasiado de tu serena belleza darte vida en mi prosa<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">As\u00ed me habl\u00f3 el poeta cuando el d\u00eda desterraba las sombras<\/div>\n<div style=\"text-align: justify;\">Y aquella voz hecha de versos escritos con hebras del agua<\/div>\n<div style=\"text-align: justify;\">como un sortilegio que llegara en las manos de un mago<\/div>\n<div style=\"text-align: justify;\">quebr\u00f3 en mil pedazos el fr\u00edo m\u00e1rmol que me aprisionaba.<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Alguien firm\u00f3 un vale por\u2026<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Alguien firm\u00f3 un vale por mis sue\u00f1os.<\/div>\n<div style=\"text-align: justify;\">\u00bfMi pagar\u00e9 vino conmigo o yo con \u00e9l?<\/div>\n<div style=\"text-align: justify;\">Somos uno, luz y sombre, agua y fuego,<\/div>\n<div style=\"text-align: justify;\">vamos juntos desde la cuna a la fosa.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00bfQui\u00e9n antes que yo adquiri\u00f3 la deuda?<\/div>\n<div style=\"text-align: justify;\">\u00bfAcaso mis genes no fueron pagados?<\/div>\n<div style=\"text-align: justify;\">\u00bfO mi primer ancestro olvid\u00f3 la deuda<\/div>\n<div style=\"text-align: justify;\">y los intereses a mi cuenta los cargaron?<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00bfPor qu\u00e9 sobre mis hombros encorvados<\/div>\n<div style=\"text-align: justify;\">cuelgan las deudas de multinacionales<\/div>\n<div style=\"text-align: justify;\">industrias forestales y gigantes petroleras<\/div>\n<div style=\"text-align: justify;\">sin detenerse a preguntar si yo las quiero?<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Debo las cuentas de razas extinguidas.<\/div>\n<div style=\"text-align: justify;\">F\u00e9retros de muertos de no conoc\u00ed.<\/div>\n<div style=\"text-align: justify;\">El t\u00e1lamo fr\u00edo donde reposar\u00e1n un d\u00eda<\/div>\n<div style=\"text-align: justify;\">mis huesos, el agua que bebo, el aire, el temor.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u00bfQu\u00e9 valor tendr\u00e1 el \u00faltimo suspiro que exhale?<\/div>\n<div style=\"text-align: justify;\">\u00bfQui\u00e9n pagar\u00e1 cuando triunfe el amor?<\/div>\n<div style=\"text-align: justify;\">\u00bfCu\u00e1nto estoy debiendo por mirar la luna?<\/div>\n<div style=\"text-align: justify;\">Me han hipotecado hasta la luz del sol.<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-weight: bold;\">Unas palabras para su primer libro<\/span><\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Bajo un bello t\u00edtulo: \u201cMariposas en la ci\u00e9naga\u201d, vemos levantar el vuelo \u00e1gil y colorido a una poetisa que desconoc\u00edamos. Y nos parece atinad\u00edsima esta figura de equilibrado contraste para representar el encuentro entre uno y otro elemento. El primero de ellos nos recuerda la mutaci\u00f3n, aquella curiosa metamorfosis a la que tambi\u00e9n se refiri\u00f3 Kafka en su momento, sobre una superficie que no ha cambiado tanto desde entonces; nos refiere el sentido del desplazamiento que sortea las dificultades y las brumas, con un destello de libertad y de belleza que surge, no importa de d\u00f3nde; simplemente aparece y se multiplica como la expresi\u00f3n m\u00e1gica, evanescente, huidiza, pero infinita que tiene la vida despu\u00e9s de todo. El segundo elemento (la ci\u00e9naga) es el humedal fecundador, la desmaterializaci\u00f3n que antecede a la sorprendente creaci\u00f3n humana y divina; el fango, el amasijo originario, donde est\u00e1n los vapores primeros que conforman la naturaleza y su qu\u00edmica en actividad. Aunque la idea de la miasma aparenta la oposici\u00f3n a todo orden de belleza y de bienestar para el esp\u00edritu, en la s\u00edntesis de esta conjunci\u00f3n se concilian los factores universales de la creaci\u00f3n y el absoluto, donde el color de la mariposa, el encanto de sus movimientos y su conjunto, encuentran una curiosa armon\u00eda con la fuente de la que escapan a manifestarse por el universo. Por eso es que la autora nos habla de que \u201cla luz desterrar\u00e1 a las sombras\u201d, y que \u201cun canto de vida se elevar\u00e1 de las piedras\u201d, porque en su inconsciente creador la firmeza que impulsa su vuelo se sustenta tambi\u00e9n en aquellos pesares o sombras de las que escapa, las que dan tambi\u00e9n su energ\u00eda para el impulso. Al creer en \u201c\u2026la luz que arrasa las tinieblas\u2026\u201d, la autora se sit\u00faa en el centro del instante vital, donde se conjugan oscuridades y rayos espl\u00e9ndidos que le ofrecen este soplo m\u00e1gico del sue\u00f1o trascendental; es su ascenso al cosmos o su regreso a \u00e9ste, con la estela de sus pesares y de sus alegr\u00edas, cuando el sol toca la escarcha o el granizo; entonces decir: \u201c\u2026A veces me sue\u00f1o \u00e1rbol.\/ Pulpa h\u00fameda y olorosa,\/ verde follaje quejumbroso, \/ nudos amargos destilando\/ gotas de sangre vegetal,\u2026\/ A veces me sue\u00f1o ave.\/ Liviano cuerpo que se remonta\u2026\/,\u201d representa este peregrinaje universal que lleva la direcci\u00f3n de hacer de su sue\u00f1o una realidad; pero m\u00e1s que eso, hacer de su instante breve, un tr\u00e1nsito superior; extraer de sus sinsabores esa sustancia vivificante, en cuya dimensi\u00f3n, la poetisa, m\u00e1gica y vaticinante vislumbra un porvenir de armon\u00eda, donde confluyen tanto mariposas como aguas detenidas que las reflejan al fin y al cabo y reproducen la imagen sorprendente. Felicito a esta mujer que escribe versos con la misma ternura y verdad que le entreg\u00f3 a la multiplicaci\u00f3n sagrada, cobijando a sus hijas, a quienes ve c\u00f3mo alzan tambi\u00e9n su vuelo igual que hacen las mariposas. Invito a leer estos poemas, escritos en el centro de lo desconocido (el universo) por qui\u00e9n es una necesaria parte de \u00e9l.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">LUIS CONTRERAS JARA<\/div>\n<div style=\"text-align: justify;\">Poeta y escritor<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nac\u00ed en la ciudad de Concepci\u00f3n un 18 de Mayo de 1954. Por razones de trabajo, mis padres fueron trasladados a Yumbel en donde curs\u00e9 mi ense\u00f1anza b\u00e1sica en la Escuela Superior de Ni\u00f1as y en el Liceo Fiscal hasta 1\u00ba Medio terminando mi ense\u00f1anza secundaria en el Liceo de Ni\u00f1as N\u00ba1 en Concepci\u00f3n. Ingres\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115,30,112,67],"tags":[],"class_list":["post-4926","post","type-post","status-publish","format-standard","hentry","category-alicia-pereda","category-creadores","category-opinion","category-poesia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alicia Pereda Saavedra. Palabra de Mujer - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alicia Pereda Saavedra. Palabra de Mujer - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Nac\u00ed en la ciudad de Concepci\u00f3n un 18 de Mayo de 1954. Por razones de trabajo, mis padres fueron trasladados a Yumbel en donde curs\u00e9 mi ense\u00f1anza b\u00e1sica en la Escuela Superior de Ni\u00f1as y en el Liceo Fiscal hasta 1\u00ba Medio terminando mi ense\u00f1anza secundaria en el Liceo de Ni\u00f1as N\u00ba1 en Concepci\u00f3n. Ingres\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-03T05:19:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-30T12:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s200\/alicia.bmp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Alicia Pereda Saavedra. Palabra de Mujer\",\"datePublished\":\"2009-06-03T05:19:00+00:00\",\"dateModified\":\"2021-09-30T12:43:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/\"},\"wordCount\":1488,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/3.bp.blogspot.com\\\/_2S_RxGRVjis\\\/SiYKIxhbFWI\\\/AAAAAAAAIxo\\\/4-BAwmg7-hE\\\/s200\\\/alicia.bmp\",\"articleSection\":[\"Alicia Pereda\",\"Creadores\",\"Opini\u00f3n\",\"Poes\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/\",\"name\":\"Alicia Pereda Saavedra. Palabra de Mujer - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/3.bp.blogspot.com\\\/_2S_RxGRVjis\\\/SiYKIxhbFWI\\\/AAAAAAAAIxo\\\/4-BAwmg7-hE\\\/s200\\\/alicia.bmp\",\"datePublished\":\"2009-06-03T05:19:00+00:00\",\"dateModified\":\"2021-09-30T12:43:31+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/3.bp.blogspot.com\\\/_2S_RxGRVjis\\\/SiYKIxhbFWI\\\/AAAAAAAAIxo\\\/4-BAwmg7-hE\\\/s200\\\/alicia.bmp\",\"contentUrl\":\"https:\\\/\\\/3.bp.blogspot.com\\\/_2S_RxGRVjis\\\/SiYKIxhbFWI\\\/AAAAAAAAIxo\\\/4-BAwmg7-hE\\\/s200\\\/alicia.bmp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alicia-pereda-saavedra-palabra-de-mujer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alicia Pereda Saavedra. Palabra de Mujer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alicia Pereda Saavedra. Palabra de Mujer - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/","og_locale":"es_ES","og_type":"article","og_title":"Alicia Pereda Saavedra. Palabra de Mujer - Nuestro Bio B\u00edo","og_description":"Nac\u00ed en la ciudad de Concepci\u00f3n un 18 de Mayo de 1954. Por razones de trabajo, mis padres fueron trasladados a Yumbel en donde curs\u00e9 mi ense\u00f1anza b\u00e1sica en la Escuela Superior de Ni\u00f1as y en el Liceo Fiscal hasta 1\u00ba Medio terminando mi ense\u00f1anza secundaria en el Liceo de Ni\u00f1as N\u00ba1 en Concepci\u00f3n. Ingres\u00e9 [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-06-03T05:19:00+00:00","article_modified_time":"2021-09-30T12:43:31+00:00","og_image":[{"url":"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s200\/alicia.bmp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/"},"author":{"name":"","@id":""},"headline":"Alicia Pereda Saavedra. Palabra de Mujer","datePublished":"2009-06-03T05:19:00+00:00","dateModified":"2021-09-30T12:43:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/"},"wordCount":1488,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s200\/alicia.bmp","articleSection":["Alicia Pereda","Creadores","Opini\u00f3n","Poes\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/","url":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/","name":"Alicia Pereda Saavedra. Palabra de Mujer - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s200\/alicia.bmp","datePublished":"2009-06-03T05:19:00+00:00","dateModified":"2021-09-30T12:43:31+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#primaryimage","url":"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s200\/alicia.bmp","contentUrl":"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/SiYKIxhbFWI\/AAAAAAAAIxo\/4-BAwmg7-hE\/s200\/alicia.bmp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/alicia-pereda-saavedra-palabra-de-mujer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Alicia Pereda Saavedra. Palabra de Mujer"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=4926"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4926\/revisions"}],"predecessor-version":[{"id":7242,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/4926\/revisions\/7242"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=4926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=4926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=4926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}