{"id":5099,"date":"2009-03-10T17:25:00","date_gmt":"2009-03-10T17:25:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/03\/10\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/"},"modified":"2022-10-05T23:38:17","modified_gmt":"2022-10-05T23:38:17","slug":"libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/","title":{"rendered":"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local"},"content":{"rendered":"<div style=\"text-align: justify;\">Este viernes 13 de marzo, se realizar\u00e1 el lanzamiento del libro \u201cArte-Danza-Entorno, Cr\u00f3nica Historiogr\u00e1fica de Calauc\u00e1n\u201d. La actividad ser\u00e1 las 22:00 hrs. en el Sal\u00f3n Mural del Gobierno Regional, ubicado en Av. Prat 525.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El libro confeccionado por sus protagonistas e investigadores, entrega la historia documentada de la Academia Calauc\u00e1n, destacando el car\u00e1cter art\u00edstico-social de \u00e9ste. Asimismo, da a conocer la historiograf\u00eda cultural que le ha llevado a ser un referente en cuanto al desarrollo de la danza local, constituy\u00e9ndose en una herramienta para la conservaci\u00f3n y ampliaci\u00f3n de la memoria.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes 13 de marzo, se realizar\u00e1 el lanzamiento del libro \u201cArte-Danza-Entorno, Cr\u00f3nica Historiogr\u00e1fica de Calauc\u00e1n\u201d. La actividad ser\u00e1 las 22:00 hrs. en el Sal\u00f3n Mural del Gobierno Regional, ubicado en Av. Prat 525. El libro confeccionado por sus protagonistas e investigadores, entrega la historia documentada de la Academia Calauc\u00e1n, destacando el car\u00e1cter art\u00edstico-social de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[212,70],"tags":[],"class_list":["post-5099","post","type-post","status-publish","format-standard","hentry","category-danza","category-libros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Este viernes 13 de marzo, se realizar\u00e1 el lanzamiento del libro \u201cArte-Danza-Entorno, Cr\u00f3nica Historiogr\u00e1fica de Calauc\u00e1n\u201d. La actividad ser\u00e1 las 22:00 hrs. en el Sal\u00f3n Mural del Gobierno Regional, ubicado en Av. Prat 525. El libro confeccionado por sus protagonistas e investigadores, entrega la historia documentada de la Academia Calauc\u00e1n, destacando el car\u00e1cter art\u00edstico-social de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-10T17:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T23:38:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local\",\"datePublished\":\"2009-03-10T17:25:00+00:00\",\"dateModified\":\"2022-10-05T23:38:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/\"},\"wordCount\":116,\"commentCount\":0,\"articleSection\":[\"Danza\",\"Libros\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/\",\"name\":\"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2009-03-10T17:25:00+00:00\",\"dateModified\":\"2022-10-05T23:38:17+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/","og_locale":"es_ES","og_type":"article","og_title":"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local - Nuestro Bio B\u00edo","og_description":"Este viernes 13 de marzo, se realizar\u00e1 el lanzamiento del libro \u201cArte-Danza-Entorno, Cr\u00f3nica Historiogr\u00e1fica de Calauc\u00e1n\u201d. La actividad ser\u00e1 las 22:00 hrs. en el Sal\u00f3n Mural del Gobierno Regional, ubicado en Av. Prat 525. El libro confeccionado por sus protagonistas e investigadores, entrega la historia documentada de la Academia Calauc\u00e1n, destacando el car\u00e1cter art\u00edstico-social de [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-03-10T17:25:00+00:00","article_modified_time":"2022-10-05T23:38:17+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/"},"author":{"name":"","@id":""},"headline":"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local","datePublished":"2009-03-10T17:25:00+00:00","dateModified":"2022-10-05T23:38:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/"},"wordCount":116,"commentCount":0,"articleSection":["Danza","Libros"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/","url":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/","name":"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2009-03-10T17:25:00+00:00","dateModified":"2022-10-05T23:38:17+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/libro-de-historia-del-calaucan-apuesta-a-la-conservacion-de-la-memoria-dancistica-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Libro de historia del Calauc\u00e1n apuesta a la conservaci\u00f3n de la memoria danc\u00edstica local"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=5099"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5099\/revisions"}],"predecessor-version":[{"id":14175,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5099\/revisions\/14175"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=5099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=5099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=5099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}