{"id":5187,"date":"2009-01-13T22:50:00","date_gmt":"2009-01-13T22:50:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2009\/01\/13\/la-historia-de-la-cultura-hip-hop\/"},"modified":"2009-01-13T22:50:00","modified_gmt":"2009-01-13T22:50:00","slug":"la-historia-de-la-cultura-hip-hop","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/","title":{"rendered":"La Historia de la Cultura Hip-Hop"},"content":{"rendered":"<div style=\"clear: both; text-align: center;\"><a href=\"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s1600\/hip-hop.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-original-height=\"494\" data-original-width=\"1023\" height=\"154\" src=\"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s320\/hip-hop.jpg\" width=\"320\" \/><\/a><\/div>\n<div style=\"text-align: justify;\">Las ra\u00edces de la Cultura Hip-Hop se remontan a las bases de la cultura \u00abAFROAMERICANA\u00bb que se desarroll\u00f3 en los Estados Unidos y su historia. Se remontan a estas bases por ser un \u00abmovimiento negro\u00bb en un principio.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La Cultura Hip-Hop se compone de cuatro modos b\u00e1sicos de expresi\u00f3n. DJing, MCing, B-Boying y Graffitti. De ellos nace la Cultura Hip-Hop. Estos provienen de influencias musicales, culturales, sociales, religiosas, econ\u00f3micas, etc&#8230; A estas se les fueron a\u00f1adiendo otros artes y modos de expresi\u00f3n que han pasado a ser parte de esta cultura. Tales como filosof\u00edas, poes\u00eda y modas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La Cultura Hip-Hop sigue creciendo cada d\u00eda. Esto gracias a las grandes aportaciones de otra culturas y por la accesibilidad en las comunicaciones que cada d\u00eda aumentan las relaciones entre culturas distantes y permite el enriquecimiento de unas con otras. Cuando se refiere a esta sub-cultura musical se tiene que pensar principalmente en cuatro formas de expresi\u00f3n:<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">&#8211; Emceen\/rap, <\/div>\n<div style=\"text-align: justify;\">&#8211; dj\/urntablism, <\/div>\n<div style=\"text-align: justify;\">&#8211; b-boying\/break dance y <\/div>\n<div style=\"text-align: justify;\">&#8211; graffitti. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Estas son la voz, la m\u00fasica, el baile y la arte en esta cultura. Cada una de estas expresiones tiene identidad propia y su importancia individual, pero todas y cada una de ellas se entrelazan.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El emceen, que es de donde viene el \u00abt\u00e9rmino MC\u00bb o como lo llamamos hoy en d\u00eda rap o raggamufin viene de una tradici\u00f3n africana que se conserva en Jamaica y que fue llevada al N.Y. a principios de los 70s por un DJ jamaiquino conocido como Kool Herc. El emccen de esta \u00e9poca en la m\u00fasica jamaiquina se basaba en decir frases para animar al p\u00fablico, esto haci\u00e9ndolo sobre los \u00abdubs\u00bb o parte instrumental de los discos. Kool Herc lo adapta a la m\u00fasica de moda en Nueva York como James Brown y crea lo que hoy conocemos. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Con los a\u00f1os este arte se ha desarrollado a grandes niveles, tanto as\u00ed como que se ha fusionado la poes\u00eda urbana y negroide con el mecen.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El DJing de la cultura Hip-Hop nace con DJ Kool Herc, de una manera muy cercana al emceen que hab\u00eda creado. El estilo jamaiquino de emceen es con m\u00fasica jamaiquina y es llamado Dee Jaying o Toasting, y en la m\u00fasica jamaiquina desde los 70s existe el \u00abdub\u00bb, en base a esto el crea una manera de alargar los \u00abbreak parts\u00bb o partes instrumentales o de percusi\u00f3n de los discos. Lo hace utilizando dos discos id\u00e9nticos y un \u00abaudio mixer&#8217;. Esta es la primera forma de DJing.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Un turntablist es una persona que utiliza un \u00abturntable\u00bb osea un plato no solo para mezclar m\u00fasica sino para crearla. Dentro de este arte se desarrollan distintas t\u00e9cnicas pero la m\u00e1s conocido es el \u00abscratch\u00bb, que es literalmente mover el disco produciendo un sonido que el DJ maneja de la manera deseada.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El b-boying o break dance comienza en la mitad de los a\u00f1os 60s con el \u00abgood foot\u00bb una forma de baile de la \u00e9poca nombrada de esa manera por una grabaci\u00f3n de James Brown del mismo nombre. Esta forma de baile que le da origen al \u00abbreakin'\u00bb comienza cuando se empiezan pasos de baile ejecutados en el suelo.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">De ah\u00ed en adelante entran fusiones del jazz, la m\u00edmica y as\u00ed por el estilo. El b-boying en general hoy en d\u00eda es el estilo de baile dentro del Hip-Hop m\u00e1s conocido y de m\u00e1s aceptaci\u00f3n pero no es la \u00fanica forma de baile Hip-Hop.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Las formas de arte del Hip-Hop siempre han existido no son nada nuevo lo que cambia es la \u00e9poca y la realidad de Vida. Por ejemplo el b-boying y la capoeira al igual que la bomba puertorrique\u00f1a son estilos de baile hermanos, solo que se desarrollaron en lugares diferentes y en dentro de su realidad de vida. De la misma manera el graffitti, si ponemos las cosas desde una perspectiva realista el graffitti existe desde los jerogl\u00edficos solo que obviamente no era lo que es ahora.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Hay mucho m\u00e1s por discutir sobre esta cultura, pero esto hay que hacerlo objetivamente. Nadie puede hablar de un tema o una cultura sin antes no conocerla y verla desde el lado en el que est\u00e1n sus protagonistas. No podemos hablar acerca de un tema objetivamente sin antes conocer todos los factores que rodean al mismo<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Fuente: Fusi\u00f3n de estilos 2.0<\/div>\n<div style=\"text-align: justify;\"><a href=\"http:\/\/www.facebook.com\/group.php?gid=47438085489\">http:\/\/www.facebook.com\/group.php?gid=47438085489<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las ra\u00edces de la Cultura Hip-Hop se remontan a las bases de la cultura \u00abAFROAMERICANA\u00bb que se desarroll\u00f3 en los Estados Unidos y su historia. Se remontan a estas bases por ser un \u00abmovimiento negro\u00bb en un principio. La Cultura Hip-Hop se compone de cuatro modos b\u00e1sicos de expresi\u00f3n. DJing, MCing, B-Boying y Graffitti. De [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160,232,10],"tags":[],"class_list":["post-5187","post","type-post","status-publish","format-standard","hentry","category-cultura","category-hip-hop","category-historia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Historia de la Cultura Hip-Hop - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Historia de la Cultura Hip-Hop - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Las ra\u00edces de la Cultura Hip-Hop se remontan a las bases de la cultura \u00abAFROAMERICANA\u00bb que se desarroll\u00f3 en los Estados Unidos y su historia. Se remontan a estas bases por ser un \u00abmovimiento negro\u00bb en un principio. La Cultura Hip-Hop se compone de cuatro modos b\u00e1sicos de expresi\u00f3n. DJing, MCing, B-Boying y Graffitti. De [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-01-13T22:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s320\/hip-hop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Historia de la Cultura Hip-Hop\",\"datePublished\":\"2009-01-13T22:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/\"},\"wordCount\":770,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/-uK44iSZHZdQ\\\/WpYVPt6Uz8I\\\/AAAAAAAAc4w\\\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\\\/s320\\\/hip-hop.jpg\",\"articleSection\":[\"Cultura\",\"Hip-Hop\",\"Historia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/\",\"name\":\"La Historia de la Cultura Hip-Hop - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/-uK44iSZHZdQ\\\/WpYVPt6Uz8I\\\/AAAAAAAAc4w\\\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\\\/s320\\\/hip-hop.jpg\",\"datePublished\":\"2009-01-13T22:50:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/4.bp.blogspot.com\\\/-uK44iSZHZdQ\\\/WpYVPt6Uz8I\\\/AAAAAAAAc4w\\\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\\\/s320\\\/hip-hop.jpg\",\"contentUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/-uK44iSZHZdQ\\\/WpYVPt6Uz8I\\\/AAAAAAAAc4w\\\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\\\/s320\\\/hip-hop.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/la-historia-de-la-cultura-hip-hop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Historia de la Cultura Hip-Hop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Historia de la Cultura Hip-Hop - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/","og_locale":"es_ES","og_type":"article","og_title":"La Historia de la Cultura Hip-Hop - Nuestro Bio B\u00edo","og_description":"Las ra\u00edces de la Cultura Hip-Hop se remontan a las bases de la cultura \u00abAFROAMERICANA\u00bb que se desarroll\u00f3 en los Estados Unidos y su historia. Se remontan a estas bases por ser un \u00abmovimiento negro\u00bb en un principio. La Cultura Hip-Hop se compone de cuatro modos b\u00e1sicos de expresi\u00f3n. DJing, MCing, B-Boying y Graffitti. De [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2009-01-13T22:50:00+00:00","og_image":[{"url":"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s320\/hip-hop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/"},"author":{"name":"","@id":""},"headline":"La Historia de la Cultura Hip-Hop","datePublished":"2009-01-13T22:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/"},"wordCount":770,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s320\/hip-hop.jpg","articleSection":["Cultura","Hip-Hop","Historia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/","url":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/","name":"La Historia de la Cultura Hip-Hop - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s320\/hip-hop.jpg","datePublished":"2009-01-13T22:50:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#primaryimage","url":"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s320\/hip-hop.jpg","contentUrl":"https:\/\/4.bp.blogspot.com\/-uK44iSZHZdQ\/WpYVPt6Uz8I\/AAAAAAAAc4w\/XlcY3RgLOh8ZSuhvRrkwih0Bp6SnK5_SwCLcBGAs\/s320\/hip-hop.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/la-historia-de-la-cultura-hip-hop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"La Historia de la Cultura Hip-Hop"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=5187"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5187\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=5187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=5187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=5187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}