{"id":5222,"date":"2008-11-14T01:46:00","date_gmt":"2008-11-14T01:46:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2008\/11\/14\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/"},"modified":"2008-11-14T01:46:00","modified_gmt":"2008-11-14T01:46:00","slug":"ganadores-de-premios-regionales-de-arte-y-cultura-2008","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/","title":{"rendered":"Ganadores de Premios Regionales de Arte y Cultura 2008"},"content":{"rendered":"<div style=\"text-align: justify;\">Treinta y nueve artistas de la regi\u00f3n postularon este a\u00f1o para convertirse en uno de ganadores de los Premios de Arte y Cultura 2008. S\u00f3lo cuatro de ellos obtuvieron la mayor\u00eda de los votos por parte del Jurado, el cual se reuni\u00f3 el lunes en la oficina de Enlace del Consejo Regional de la Cultura y las Artes para evaluar detalladamente la trayectoria de cada uno de los postulantes. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Luego de dos horas de debate para llegar a un concilio final, se dieron a conocer los nombres de los artistas que recibir\u00e1n en diciembre, el reconocimiento p\u00fablico por sus respectivos aportes al desarrollo de la cultura local y fortalecimiento de la identidad Regional.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Brisolia Herrera, en la categor\u00eda Artes Esc\u00e9nicas: Tennyson Ferrada; Osvaldo C\u00e1ceres, en la categor\u00eda Ciencias y Tecnolog\u00eda: Pascual Binimelis; Alejandra Urrutia, en la categor\u00eda Artes Musicales: Claudio Arrau; y Ram\u00f3n Riquelme, en la categor\u00eda Artes Literarias: Baldomero Lillo, son los artistas escogidos. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El Jurado estuvo compuesto por la Intendenta Regional, Mar\u00eda Ang\u00e9lica Fuentes; el Director Regional del Consejo Nacional de la Cultura y las Artes de la Regi\u00f3n del B\u00edo B\u00edo, Luis Aguirre; integrantes del Directorio del CRCA, Marcela Rosen, Bernab\u00e9 Carrasco, Alejandro Witker, Rodrigo Pirac\u00e9s y Rodrigo Mart\u00ednez; en representaci\u00f3n del Comit\u00e9 Consultivo, Antonio Cort\u00e9z; el Presidente de la Comisi\u00f3n de Cultura del Consejo Regional de Gobierno, Bernardo Daroch y Am\u00e9rico Giusti, galardonado en la versi\u00f3n pasada de este Certamen. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Los \u201cPremios Regionales de Arte y Cultura de la Regi\u00f3n del B\u00edo B\u00edo\u201d que entrega el Gobierno Regional, a trav\u00e9s del Consejo Nacional de la Cultura y las Artes, est\u00e1n destinados a reconocer la obra de chilenos nacidos o no en la regi\u00f3n o el pa\u00eds. De esta forma, diferentes organizaciones e instituciones postulan una personalidad en las artes: Literarias, Visuales, Esc\u00e9nicas, Musicales; Cultura Tradicional, Ciencia Y Tecnolog\u00eda, Ciencias Sociales y Artes Audiovisuales. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Antecedentes de los premiados <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Brisolia Herrera: Profesora de Pedagog\u00eda en Espa\u00f1ol, actriz profesional. Realiz\u00f3 giras con el TUC y el Teatro Experimental desde Arica a Punta Arenas y tambi\u00e9n en Uruguay, Montevideo, Argentina, entre otros pa\u00edses.Entre las obras realizadas en el Teatro Universidad de Concepci\u00f3n, podemos destacar \u201cLa vida es Sue\u00f1o\u201d, \u00b7Asesinato en la Catedral\u201d, \u201cEl ensayo de la comedia\u201d, \u201cLa zapatera prodigiosa\u201d y \u201cLos papeles del infierno\u201d. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Osvaldo C\u00e1ceres: Arquitecto de la Facultad de Arquitectura de la Universidad de Chile, gestor cultural y defensor del patrimonio hist\u00f3rico y arquitect\u00f3nico en la Provincia del B\u00edo B\u00edo, como la defensa de la capilla del Hospital de Los \u00c1ngeles, su apoyo a la constituci\u00f3n de un Centro Cultural para la ciudad en el emblem\u00e1tico edificio del ex Liceo de Hombres. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Alejandra Urrutia: Directora de la Orquesta del Bicentenario de Curanilahue y Profesora de la Escuela Art\u00edstica del Liceo Mariano Latorre. Violinista de destacada excelencia art\u00edstica y reconocida por sus logros obtenidos como Directora de Orquestas, tanto en Chile como en el extranjero, donde se ha destacado en pa\u00edses como Argentina, Estados Unidos y Francia. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ram\u00f3n Riquelme: Inicia su voz po\u00e9tica en 1965, a\u00f1o en que se publican sus primeros textos. La formaci\u00f3n cultural, pol\u00edtica y humana la vivi\u00f3 intensamente en Chill\u00e1n, pero a mediados de los a\u00f1os 70 se traslada a Quinchamal\u00ed. Como periodista, sus textos han sido iluminados por su prodigiosa memoria n datos fechas y recuerdos. Como poeta, crea climas intensos, sentenciosos, finos y cultos. Su residencia en Quinchamal\u00ed le ha sido de gran aporte a su poes\u00eda, a trav\u00e9s de la cual ha logrado un desarrollo incesante, m\u00edtico y marginal. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Autor de los poemas \u201cLa sopa de los domingos\u201d, \u201cR\u00e9quiem\u201d, \u201cSexteto en tres movimientos\u201d, \u201cLos castigos\u201d y \u201cAnulaci\u00f3n del sue\u00f1o\u201d, entre otros.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Fuente: Consejo Regional de la Cultura y las Artes, Regi\u00f3n del Bio B\u00edo<\/div>\n<div style=\"text-align: justify;\">www.culturabiobio.cl<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Treinta y nueve artistas de la regi\u00f3n postularon este a\u00f1o para convertirse en uno de ganadores de los Premios de Arte y Cultura 2008. S\u00f3lo cuatro de ellos obtuvieron la mayor\u00eda de los votos por parte del Jurado, el cual se reuni\u00f3 el lunes en la oficina de Enlace del Consejo Regional de la Cultura [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-5222","post","type-post","status-publish","format-standard","hentry","category-creadores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ganadores de Premios Regionales de Arte y Cultura 2008 - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ganadores de Premios Regionales de Arte y Cultura 2008 - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Treinta y nueve artistas de la regi\u00f3n postularon este a\u00f1o para convertirse en uno de ganadores de los Premios de Arte y Cultura 2008. S\u00f3lo cuatro de ellos obtuvieron la mayor\u00eda de los votos por parte del Jurado, el cual se reuni\u00f3 el lunes en la oficina de Enlace del Consejo Regional de la Cultura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-14T01:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ganadores de Premios Regionales de Arte y Cultura 2008\",\"datePublished\":\"2008-11-14T01:46:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/\"},\"wordCount\":688,\"commentCount\":0,\"articleSection\":[\"Creadores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/\",\"name\":\"Ganadores de Premios Regionales de Arte y Cultura 2008 - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2008-11-14T01:46:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ganadores de Premios Regionales de Arte y Cultura 2008\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ganadores de Premios Regionales de Arte y Cultura 2008 - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/","og_locale":"es_ES","og_type":"article","og_title":"Ganadores de Premios Regionales de Arte y Cultura 2008 - Nuestro Bio B\u00edo","og_description":"Treinta y nueve artistas de la regi\u00f3n postularon este a\u00f1o para convertirse en uno de ganadores de los Premios de Arte y Cultura 2008. S\u00f3lo cuatro de ellos obtuvieron la mayor\u00eda de los votos por parte del Jurado, el cual se reuni\u00f3 el lunes en la oficina de Enlace del Consejo Regional de la Cultura [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2008-11-14T01:46:00+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/"},"author":{"name":"","@id":""},"headline":"Ganadores de Premios Regionales de Arte y Cultura 2008","datePublished":"2008-11-14T01:46:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/"},"wordCount":688,"commentCount":0,"articleSection":["Creadores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/","url":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/","name":"Ganadores de Premios Regionales de Arte y Cultura 2008 - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2008-11-14T01:46:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/ganadores-de-premios-regionales-de-arte-y-cultura-2008\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Ganadores de Premios Regionales de Arte y Cultura 2008"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=5222"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5222\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=5222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=5222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=5222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}