{"id":5305,"date":"2010-06-05T06:42:00","date_gmt":"2010-06-05T06:42:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2010\/06\/05\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/"},"modified":"2022-10-05T21:34:32","modified_gmt":"2022-10-05T21:34:32","slug":"segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/","title":{"rendered":"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte"},"content":{"rendered":"<div style=\"text-align: justify;\"><a href=\"http:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s1600\/Foto+Orquesta+1.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5479178480547820914\" src=\"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s400\/Foto+Orquesta+1.jpg\" style=\"height: 300px; width: 400px;\" \/><\/a>Los tradicionales conciertos de C\u00e1mara de la Orquesta Sinf\u00f3nica Universidad de Concepci\u00f3n, retornar\u00e1n desde este s\u00e1bado a la Casa del Arte, donde habitualmente se desarrolla esta temporada, tras un primer concierto que, por causa del terremoto, se realiz\u00f3 de forma extraordinaria en abril en el teatro universitario.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Y como ser\u00e1 la t\u00f3nica durante todo este a\u00f1o, los Conciertos de C\u00e1mara ser\u00e1n dirigidos por los propios m\u00fasicos de la Orquesta Sinf\u00f3nica. As\u00ed, las obras a interpretar son: Concierto en Sol menor para flauta, oboe, fagot y clavec\u00edn, de Antonio Vivaldi, con los m\u00fasicos Gabriela Godoy (flauta), Marcela Iba\u00f1ez (fagot), Maria C. San Mart\u00edn (oboe) y Ver\u00f3nica Torres (clavecin); Tr\u00edo, de Claude Debussy, con los m\u00fasicos Claudio Morales (viola) , Carolina Cavero (flauta)  y Patricia Reyes (arpa); Madrigal Sonata, de Bohuslav Martinu, con los m\u00fasicos Carolina Cavero (flauta), Ricardo Olivos (viol\u00edn) y Ver\u00f3nica Torres (piano); Sonata, de M. Emmanuel, con los m\u00fasicos Carolina Cavero (flauta), Vladimir Jara (clarinete) y Ver\u00f3nica Torres (piano); Musikalisches Blumeng\u00e4rtlein und Leyptziger Allerley, de Paul Hindemith, con los m\u00fasicos Vladimir Jara (clarinete) y Maria Teresa Molina (contrabajo); y finalmente, Tr\u00edo, de Francisc Poulenc, con los m\u00fasicos Javier Bustos (oboe), Patricia Iribarren (fagot) y Ver\u00f3nica Torres (piano).<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El Segundo Concierto de C\u00e1mara de la Temporada 2010 se realizar\u00e1 el 05 de junio a las 19 horas en la Casa del Arte de la Universidad de Concepci\u00f3n, con entrada liberada, sin invitaciones.<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los tradicionales conciertos de C\u00e1mara de la Orquesta Sinf\u00f3nica Universidad de Concepci\u00f3n, retornar\u00e1n desde este s\u00e1bado a la Casa del Arte, donde habitualmente se desarrolla esta temporada, tras un primer concierto que, por causa del terremoto, se realiz\u00f3 de forma extraordinaria en abril en el teatro universitario. Y como ser\u00e1 la t\u00f3nica durante todo este [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[],"class_list":["post-5305","post","type-post","status-publish","format-standard","hentry","category-musica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Los tradicionales conciertos de C\u00e1mara de la Orquesta Sinf\u00f3nica Universidad de Concepci\u00f3n, retornar\u00e1n desde este s\u00e1bado a la Casa del Arte, donde habitualmente se desarrolla esta temporada, tras un primer concierto que, por causa del terremoto, se realiz\u00f3 de forma extraordinaria en abril en el teatro universitario. Y como ser\u00e1 la t\u00f3nica durante todo este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-05T06:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T21:34:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s400\/Foto+Orquesta+1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte\",\"datePublished\":\"2010-06-05T06:42:00+00:00\",\"dateModified\":\"2022-10-05T21:34:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/\"},\"wordCount\":279,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TAnzzFIEdXI\\\/AAAAAAAAQJU\\\/sJU9AEbdqGE\\\/s400\\\/Foto+Orquesta+1.jpg\",\"articleSection\":[\"M\u00fasica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/\",\"name\":\"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TAnzzFIEdXI\\\/AAAAAAAAQJU\\\/sJU9AEbdqGE\\\/s400\\\/Foto+Orquesta+1.jpg\",\"datePublished\":\"2010-06-05T06:42:00+00:00\",\"dateModified\":\"2022-10-05T21:34:32+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TAnzzFIEdXI\\\/AAAAAAAAQJU\\\/sJU9AEbdqGE\\\/s400\\\/Foto+Orquesta+1.jpg\",\"contentUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TAnzzFIEdXI\\\/AAAAAAAAQJU\\\/sJU9AEbdqGE\\\/s400\\\/Foto+Orquesta+1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/","og_locale":"es_ES","og_type":"article","og_title":"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte - Nuestro Bio B\u00edo","og_description":"Los tradicionales conciertos de C\u00e1mara de la Orquesta Sinf\u00f3nica Universidad de Concepci\u00f3n, retornar\u00e1n desde este s\u00e1bado a la Casa del Arte, donde habitualmente se desarrolla esta temporada, tras un primer concierto que, por causa del terremoto, se realiz\u00f3 de forma extraordinaria en abril en el teatro universitario. Y como ser\u00e1 la t\u00f3nica durante todo este [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2010-06-05T06:42:00+00:00","article_modified_time":"2022-10-05T21:34:32+00:00","og_image":[{"url":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s400\/Foto+Orquesta+1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/"},"author":{"name":"","@id":""},"headline":"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte","datePublished":"2010-06-05T06:42:00+00:00","dateModified":"2022-10-05T21:34:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/"},"wordCount":279,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s400\/Foto+Orquesta+1.jpg","articleSection":["M\u00fasica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/","url":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/","name":"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s400\/Foto+Orquesta+1.jpg","datePublished":"2010-06-05T06:42:00+00:00","dateModified":"2022-10-05T21:34:32+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#primaryimage","url":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s400\/Foto+Orquesta+1.jpg","contentUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TAnzzFIEdXI\/AAAAAAAAQJU\/sJU9AEbdqGE\/s400\/Foto+Orquesta+1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/segundo-concierto-de-camara-de-la-orquesta-sinfonica-universidad-de-concepcion-se-realizara-en-la-casa-del-arte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Segundo Concierto De C\u00e1mara De La Orquesta Sinf\u00f3nica Universidad De Concepci\u00f3n Se Realizar\u00e1 En La Casa Del Arte"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=5305"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5305\/revisions"}],"predecessor-version":[{"id":14110,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/5305\/revisions\/14110"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=5305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=5305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=5305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}