{"id":6137,"date":"2011-07-18T13:52:00","date_gmt":"2011-07-18T13:52:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2011\/07\/18\/alerta-de-heladas-en-la-region-del-bio-bio\/"},"modified":"2011-07-18T13:52:00","modified_gmt":"2011-07-18T13:52:00","slug":"alerta-de-heladas-en-la-region-del-bio-bio","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/","title":{"rendered":"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo"},"content":{"rendered":"<p><a href=\"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s1600\/heladas%2Bagr%25C3%25ADcolas.jpg\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5630690765129993282\" src=\"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s320\/heladas%2Bagr%25C3%25ADcolas.jpg\" style=\"cursor: pointer; float: left; height: 218px; margin: 0px 10px 10px 0px; width: 290px;\" \/><\/a>La Direcci\u00f3n Meteorol\u00f3gica de Chile inform\u00f3, a trav\u00e9s de su subdepartamento de Meteorolog\u00eda Agr\u00edcola, que partir de hoy lunes 18 de julio se espera el ingreso de una masa de aire fr\u00edo, la que producir\u00e1 bajas temperaturas matinales sobre todo en la zona central del pa\u00eds (desde la Regi\u00f3n de Valpara\u00edso y hasta Regi\u00f3n del Bio B\u00edo).Se estima que esta condici\u00f3n persistir\u00e1 hasta la madrugada del d\u00eda mi\u00e9rcoles 20 de julio, esper\u00e1ndose valores entre los -5 y -3 grados principalmente en valles y precordillera.  <span style=\"font-weight: bold;\">Panorama Agrometeorol\u00f3gico<\/span> Durante la estaci\u00f3n invernal existen algunas especies vegetales sensibles al fr\u00edo, dependiendo de la regi\u00f3n afectada. As\u00ed, en la Quinta Regi\u00f3n, Metropolitana y parte de la Sexta son afectados principalmente paltos, c\u00edtricos.  Dependiendo de la intensidad y duraci\u00f3n de las heladas, en paltos puede alterarse la producci\u00f3n del a\u00f1o siguiente si se produce da\u00f1o significativo en las yemas de la planta.  Por otra parte, varias especies hort\u00edcolas y florales son susceptibles a da\u00f1os por bajas temperaturas.  Igual sensibilidad al fr\u00edo lo presentan los apiarios (colmenas), los cuales deben contar con algunas medidas de protecci\u00f3n. En este sentido es importante enfatizar que las temperaturas m\u00ednimas siempre son pronosticadas a nivel de cobertizo meteorol\u00f3gico, es decir, a 1,5 mt de altura.  Si un productor posee cultivos bajos, debe considerar que las temperaturas a nivel de la superficie del suelo son, como m\u00ednimo, dos grados m\u00e1s fr\u00edas que las pronosticadas, producto de la mayor densidad del aire fr\u00edo, el cual, tiende a ocupar los primeros niveles de la superficie, acrecent\u00e1ndose a\u00fan m\u00e1s en las zonas bajas del relieve local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n Meteorol\u00f3gica de Chile inform\u00f3, a trav\u00e9s de su subdepartamento de Meteorolog\u00eda Agr\u00edcola, que partir de hoy lunes 18 de julio se espera el ingreso de una masa de aire fr\u00edo, la que producir\u00e1 bajas temperaturas matinales sobre todo en la zona central del pa\u00eds (desde la Regi\u00f3n de Valpara\u00edso y hasta Regi\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143],"tags":[],"class_list":["post-6137","post","type-post","status-publish","format-standard","hentry","category-clima"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"La Direcci\u00f3n Meteorol\u00f3gica de Chile inform\u00f3, a trav\u00e9s de su subdepartamento de Meteorolog\u00eda Agr\u00edcola, que partir de hoy lunes 18 de julio se espera el ingreso de una masa de aire fr\u00edo, la que producir\u00e1 bajas temperaturas matinales sobre todo en la zona central del pa\u00eds (desde la Regi\u00f3n de Valpara\u00edso y hasta Regi\u00f3n del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-18T13:52:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s320\/heladas%2Bagr%25C3%25ADcolas.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo\",\"datePublished\":\"2011-07-18T13:52:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/\"},\"wordCount\":309,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-ee4Z_JVeLzw\\\/TiQ7aw-lTEI\\\/AAAAAAAATB8\\\/hbr2qZcbikQ\\\/s320\\\/heladas%2Bagr%25C3%25ADcolas.jpg\",\"articleSection\":[\"Clima\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/\",\"name\":\"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-ee4Z_JVeLzw\\\/TiQ7aw-lTEI\\\/AAAAAAAATB8\\\/hbr2qZcbikQ\\\/s320\\\/heladas%2Bagr%25C3%25ADcolas.jpg\",\"datePublished\":\"2011-07-18T13:52:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#primaryimage\",\"url\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-ee4Z_JVeLzw\\\/TiQ7aw-lTEI\\\/AAAAAAAATB8\\\/hbr2qZcbikQ\\\/s320\\\/heladas%2Bagr%25C3%25ADcolas.jpg\",\"contentUrl\":\"http:\\\/\\\/3.bp.blogspot.com\\\/-ee4Z_JVeLzw\\\/TiQ7aw-lTEI\\\/AAAAAAAATB8\\\/hbr2qZcbikQ\\\/s320\\\/heladas%2Bagr%25C3%25ADcolas.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/alerta-de-heladas-en-la-region-del-bio-bio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/","og_locale":"es_ES","og_type":"article","og_title":"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo - Nuestro Bio B\u00edo","og_description":"La Direcci\u00f3n Meteorol\u00f3gica de Chile inform\u00f3, a trav\u00e9s de su subdepartamento de Meteorolog\u00eda Agr\u00edcola, que partir de hoy lunes 18 de julio se espera el ingreso de una masa de aire fr\u00edo, la que producir\u00e1 bajas temperaturas matinales sobre todo en la zona central del pa\u00eds (desde la Regi\u00f3n de Valpara\u00edso y hasta Regi\u00f3n del [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2011-07-18T13:52:00+00:00","og_image":[{"url":"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s320\/heladas%2Bagr%25C3%25ADcolas.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/"},"author":{"name":"","@id":""},"headline":"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo","datePublished":"2011-07-18T13:52:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/"},"wordCount":309,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s320\/heladas%2Bagr%25C3%25ADcolas.jpg","articleSection":["Clima"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/","url":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/","name":"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#primaryimage"},"thumbnailUrl":"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s320\/heladas%2Bagr%25C3%25ADcolas.jpg","datePublished":"2011-07-18T13:52:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#primaryimage","url":"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s320\/heladas%2Bagr%25C3%25ADcolas.jpg","contentUrl":"http:\/\/3.bp.blogspot.com\/-ee4Z_JVeLzw\/TiQ7aw-lTEI\/AAAAAAAATB8\/hbr2qZcbikQ\/s320\/heladas%2Bagr%25C3%25ADcolas.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/alerta-de-heladas-en-la-region-del-bio-bio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Alerta De Heladas En La Regi\u00f3n Del Bio B\u00edo"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/6137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=6137"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/6137\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=6137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=6137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=6137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}