{"id":6146,"date":"2011-07-11T15:05:00","date_gmt":"2011-07-11T15:05:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2011\/07\/11\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/"},"modified":"2022-09-25T12:23:09","modified_gmt":"2022-09-25T12:23:09","slug":"ballenas-en-peligro-campana-cero-caza-de-ballenas","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/","title":{"rendered":"Ballenas En Peligro &#8211; Campa\u00f1a Cero Caza De Ballenas"},"content":{"rendered":"<p><a href=\"http:\/\/3.bp.blogspot.com\/-oTODNV0g7bc\/ThsSInv7ALI\/AAAAAAAATBE\/653byTFcCv4\/s1600\/ballenasenpeligro3_b.jpg\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5628112098647802034\" class=\"alignleft\" style=\"display: block; margin: 0px auto 10px; text-align: center; cursor: hand; width: 320px; height: 142px;\" src=\"http:\/\/3.bp.blogspot.com\/-oTODNV0g7bc\/ThsSInv7ALI\/AAAAAAAATBE\/653byTFcCv4\/s320\/ballenasenpeligro3_b.jpg\" alt=\"\" border=\"0\" \/><\/a>La destrucci\u00f3n mundial de las poblaciones de ballenas se inici\u00f3 con la revoluci\u00f3n industrial y la introducci\u00f3n de nuevas tecnolog\u00edas que trajeron consigo la muerte de millones de ballenas y la devastaci\u00f3n de pr\u00e1cticamente todas las especies y poblaciones de grandes cet\u00e1ceos en menos de un siglo.<\/p>\n<p>Para 1946 la sobre explotaci\u00f3n era tan evidente que las naciones balleneras decidieron reunirse y conformar una organizaci\u00f3n orientada a:<\/p>\n<p>&#8211; <span style=\"font-weight: bold;\">Regular <\/span>la Industria Ballenera<br \/>\n&#8211; <span style=\"font-weight: bold;\">Conservar <\/span>las poblaciones de Ballenas para las generaciones futuras.<\/p>\n<p><span style=\"font-weight: bold;\">As\u00ed naci\u00f3 la Comisi\u00f3n Ballenera Internacional (CBI).<\/span><\/p>\n<p>Durante sus primeros 40 a\u00f1os, los intereses pol\u00edticos y econ\u00f3micos detr\u00e1s de la matanza impidieron a la CBI cumplir con estos dos objetivos. <span style=\"font-weight: bold;\">Como resultado casi todas las especies de grandes cet\u00e1ceos fueron llevados al borde de la extinci\u00f3n<\/span>.<\/p>\n<p>En 1986 y gracias al trabajo de cientos de organizaciones civiles y millones de ciudadanos organizados, la CBI adopt\u00f3 el mayor logro en la historia del derecho internacional: <span style=\"font-weight: bold;\">la moratoria sobre la caza comercial de ballenas<\/span>.<\/p>\n<p>Gracias a la moratoria, las ballenas avanzan lentamente hacia la recuperaci\u00f3n de sus poblaciones. Pero eso no es todo. El retorno de las ballenas a lugares ancestrales donde hab\u00edan desaparecido, ha permitido a cientos de comunidades y millones de personas a nivel mundial beneficiarse directa o indirectamente del uso no letal de estos mam\u00edferos marinos a trav\u00e9s del turismo de avistaje de ballenas.<\/p>\n<p>Pero todav\u00eda no est\u00e1n a salvo. Las naciones balleneras y en particular Jap\u00f3n, han socavado, violado e incluso intentado eliminar la moratoria. En junio de 2010 las naciones balleneras estuvieron a punto de reanudar la caza comercial mediante una propuesta que promet\u00eda enga\u00f1osamente reducir el n\u00famero de ballenas cazadas actualmente bajo diversos resquicios legales a cambio de la eliminaci\u00f3n de la moratoria y la legitimaci\u00f3n de la denominada \u201ccaza cient\u00edfica\u201d de ballenas en el Santuario de Ballenas del Oc\u00e9ano Austral.<\/p>\n<p>2011 ser\u00e1 un a\u00f1o decisivo para las ballenas. Las crecientes presiones pol\u00edticas y econ\u00f3micas que buscan reanudar la caza comercial de ballenas con el fin de revitalizar la decadente industria ballenera constituyen una creciente amenaza para el futuro de las ballenas y la propia CBI.<\/p>\n<p><a href=\"http:\/\/www.cerocazadeballenas.cl\/\">\u00danete y Apoya Cero Caza De Ballenas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La destrucci\u00f3n mundial de las poblaciones de ballenas se inici\u00f3 con la revoluci\u00f3n industrial y la introducci\u00f3n de nuevas tecnolog\u00edas que trajeron consigo la muerte de millones de ballenas y la devastaci\u00f3n de pr\u00e1cticamente todas las especies y poblaciones de grandes cet\u00e1ceos en menos de un siglo. Para 1946 la sobre explotaci\u00f3n era tan evidente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13346,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[124],"tags":[],"class_list":["post-6146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ballenas En Peligro - Campa\u00f1a Cero Caza De Ballenas - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ballenas En Peligro - Campa\u00f1a Cero Caza De Ballenas - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"La destrucci\u00f3n mundial de las poblaciones de ballenas se inici\u00f3 con la revoluci\u00f3n industrial y la introducci\u00f3n de nuevas tecnolog\u00edas que trajeron consigo la muerte de millones de ballenas y la devastaci\u00f3n de pr\u00e1cticamente todas las especies y poblaciones de grandes cet\u00e1ceos en menos de un siglo. Para 1946 la sobre explotaci\u00f3n era tan evidente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-11T15:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-25T12:23:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2011\/07\/ballenasenpeligro3_b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"142\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ballenas En Peligro &#8211; Campa\u00f1a Cero Caza De Ballenas\",\"datePublished\":\"2011-07-11T15:05:00+00:00\",\"dateModified\":\"2022-09-25T12:23:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/\"},\"wordCount\":397,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/ballenasenpeligro3_b.jpg\",\"articleSection\":[\"Medio Ambiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/\",\"name\":\"Ballenas En Peligro - Campa\u00f1a Cero Caza De Ballenas - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/ballenasenpeligro3_b.jpg\",\"datePublished\":\"2011-07-11T15:05:00+00:00\",\"dateModified\":\"2022-09-25T12:23:09+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/ballenasenpeligro3_b.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/wp-content\\\/uploads\\\/2011\\\/07\\\/ballenasenpeligro3_b.jpg\",\"width\":320,\"height\":142},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ballenas-en-peligro-campana-cero-caza-de-ballenas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ballenas En Peligro &#8211; Campa\u00f1a Cero Caza De Ballenas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ballenas En Peligro - Campa\u00f1a Cero Caza De Ballenas - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/","og_locale":"es_ES","og_type":"article","og_title":"Ballenas En Peligro - Campa\u00f1a Cero Caza De Ballenas - Nuestro Bio B\u00edo","og_description":"La destrucci\u00f3n mundial de las poblaciones de ballenas se inici\u00f3 con la revoluci\u00f3n industrial y la introducci\u00f3n de nuevas tecnolog\u00edas que trajeron consigo la muerte de millones de ballenas y la devastaci\u00f3n de pr\u00e1cticamente todas las especies y poblaciones de grandes cet\u00e1ceos en menos de un siglo. Para 1946 la sobre explotaci\u00f3n era tan evidente [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2011-07-11T15:05:00+00:00","article_modified_time":"2022-09-25T12:23:09+00:00","og_image":[{"width":320,"height":142,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2011\/07\/ballenasenpeligro3_b.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/"},"author":{"name":"","@id":""},"headline":"Ballenas En Peligro &#8211; Campa\u00f1a Cero Caza De Ballenas","datePublished":"2011-07-11T15:05:00+00:00","dateModified":"2022-09-25T12:23:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/"},"wordCount":397,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2011\/07\/ballenasenpeligro3_b.jpg","articleSection":["Medio Ambiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/","url":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/","name":"Ballenas En Peligro - Campa\u00f1a Cero Caza De Ballenas - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2011\/07\/ballenasenpeligro3_b.jpg","datePublished":"2011-07-11T15:05:00+00:00","dateModified":"2022-09-25T12:23:09+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#primaryimage","url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2011\/07\/ballenasenpeligro3_b.jpg","contentUrl":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2011\/07\/ballenasenpeligro3_b.jpg","width":320,"height":142},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/ballenas-en-peligro-campana-cero-caza-de-ballenas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Ballenas En Peligro &#8211; Campa\u00f1a Cero Caza De Ballenas"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/6146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=6146"}],"version-history":[{"count":2,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/6146\/revisions"}],"predecessor-version":[{"id":13349,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/6146\/revisions\/13349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media\/13346"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=6146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=6146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=6146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}