{"id":8739,"date":"2011-05-08T02:01:00","date_gmt":"2011-05-08T02:01:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2011\/05\/08\/el-mundo-segun-monsanto\/"},"modified":"2011-05-08T02:01:00","modified_gmt":"2011-05-08T02:01:00","slug":"el-mundo-segun-monsanto","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/","title":{"rendered":"El Mundo Seg\u00fan Monsanto"},"content":{"rendered":"<p><a href=\"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s1600\/elmundosegunmonsanto-portada.jpg\"><img decoding=\"async\" style=\"cursor:pointer; cursor:hand;width: 320px; height: 226px;\" src=\"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s320\/elmundosegunmonsanto-portada.jpg\" border=\"0\" alt=\"\"id=\"BLOGGER_PHOTO_ID_5604160422695189954\" \/><\/a><\/p>\n<p>En su revelador libro \u201cEl mundo seg\u00fan Monsanto\u201d, la periodista francesa Marie-Monique Robin desenmascara la gigantesca red de influencias de la transnacional y devela irrefutablemente su prop\u00f3sito final: controlar el cultivo y la distribuci\u00f3n de alimentos a nivel mundial, cueste lo que cueste. Adem\u00e1s de tomar ventaja de la poca regulaci\u00f3n que existe sobre los transg\u00e9nicos en la mayor\u00eda de los pa\u00edses, Monsanto pasa por encima de las instituciones competentes con su \u201cprincipio de equivalencia\u201d en mano y recurre a cualquier medio con tal de conseguir autorizaci\u00f3n para introducir sus semillas. Prueba de ello es la multa de un mill\u00f3n y medio de d\u00f3lares que en 2005 la compa\u00f1\u00eda debi\u00f3 pagar por haber sobornado a un alto funcionario del Ministerio del Medioambiente de Indonesia. <\/p>\n<p>M\u00e1s grave a\u00fan es el hecho de que Michael Taylor -autor del \u201cprincipio de equivalencia\u201d- es funcionario de Monsanto y se ha pasado los \u00faltimos veinte a\u00f1os saltando de la actividad p\u00fablica a la privada en EEUU, entre la industria alimenticia y los organismos que la regulan, haciendo de este intercambio de roles un verdadero arte de la sinverg\u00fcenzura. El \u00faltimo salto lo dio este a\u00f1o: Taylor est\u00e1 de vuelta en la FDA, esta vez como Consejero General.<\/p>\n<p>El panorama es francamente desolador.<\/p>\n<p>Imagine que usted es agricultor y produce ma\u00edz org\u00e1nico. Digamos que su vecino, tambi\u00e9n agricultor, decide plantar ma\u00edz transg\u00e9nico. Sin que nadie lo note, el viento lleva algo del polen transg\u00e9nico a su plantaci\u00f3n y \u00e9sta se contamina incorporando en sus semillas los genes modificados. Al a\u00f1o siguiente, dos agentes golpean a su puerta: est\u00e1n all\u00ed para tomar muestras de sus plantas y comprobar as\u00ed que usted no est\u00e9 cultivando especies transg\u00e9nicas sin haber pagado los derechos correspondientes. Un par de semanas despu\u00e9s: \u00a1oh, sorpresa! Su ma\u00edz es ahora transg\u00e9nico y a partir de ese momento debe pagar por \u00e9l, o pierde la plantaci\u00f3n y se va a la c\u00e1rcel. Esto ya ocurre en Brasil y Argentina. <\/p>\n<p><iframe width=\"400\" height=\"390\" src=\"http:\/\/www.youtube.com\/embed\/LdIkq6ecQGw\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Informaci\u00f3n gentileza de Mauricio Olave<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su revelador libro \u201cEl mundo seg\u00fan Monsanto\u201d, la periodista francesa Marie-Monique Robin desenmascara la gigantesca red de influencias de la transnacional y devela irrefutablemente su prop\u00f3sito final: controlar el cultivo y la distribuci\u00f3n de alimentos a nivel mundial, cueste lo que cueste. Adem\u00e1s de tomar ventaja de la poca regulaci\u00f3n que existe sobre los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76,124],"tags":[],"class_list":["post-8739","post","type-post","status-publish","format-standard","hentry","category-agricultura","category-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Mundo Seg\u00fan Monsanto - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Mundo Seg\u00fan Monsanto - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"En su revelador libro \u201cEl mundo seg\u00fan Monsanto\u201d, la periodista francesa Marie-Monique Robin desenmascara la gigantesca red de influencias de la transnacional y devela irrefutablemente su prop\u00f3sito final: controlar el cultivo y la distribuci\u00f3n de alimentos a nivel mundial, cueste lo que cueste. Adem\u00e1s de tomar ventaja de la poca regulaci\u00f3n que existe sobre los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-08T02:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s320\/elmundosegunmonsanto-portada.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Mundo Seg\u00fan Monsanto\",\"datePublished\":\"2011-05-08T02:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/\"},\"wordCount\":368,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-C87MjV-zMyQ\\\/TcX6NlsMvcI\\\/AAAAAAAASuk\\\/rjUaVeEjgGU\\\/s320\\\/elmundosegunmonsanto-portada.jpg\",\"articleSection\":[\"Agricultura\",\"Medio Ambiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/\",\"name\":\"El Mundo Seg\u00fan Monsanto - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-C87MjV-zMyQ\\\/TcX6NlsMvcI\\\/AAAAAAAASuk\\\/rjUaVeEjgGU\\\/s320\\\/elmundosegunmonsanto-portada.jpg\",\"datePublished\":\"2011-05-08T02:01:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#primaryimage\",\"url\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-C87MjV-zMyQ\\\/TcX6NlsMvcI\\\/AAAAAAAASuk\\\/rjUaVeEjgGU\\\/s320\\\/elmundosegunmonsanto-portada.jpg\",\"contentUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-C87MjV-zMyQ\\\/TcX6NlsMvcI\\\/AAAAAAAASuk\\\/rjUaVeEjgGU\\\/s320\\\/elmundosegunmonsanto-portada.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/el-mundo-segun-monsanto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Mundo Seg\u00fan Monsanto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Mundo Seg\u00fan Monsanto - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/","og_locale":"es_ES","og_type":"article","og_title":"El Mundo Seg\u00fan Monsanto - Nuestro Bio B\u00edo","og_description":"En su revelador libro \u201cEl mundo seg\u00fan Monsanto\u201d, la periodista francesa Marie-Monique Robin desenmascara la gigantesca red de influencias de la transnacional y devela irrefutablemente su prop\u00f3sito final: controlar el cultivo y la distribuci\u00f3n de alimentos a nivel mundial, cueste lo que cueste. Adem\u00e1s de tomar ventaja de la poca regulaci\u00f3n que existe sobre los [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2011-05-08T02:01:00+00:00","og_image":[{"url":"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s320\/elmundosegunmonsanto-portada.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/"},"author":{"name":"","@id":""},"headline":"El Mundo Seg\u00fan Monsanto","datePublished":"2011-05-08T02:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/"},"wordCount":368,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s320\/elmundosegunmonsanto-portada.jpg","articleSection":["Agricultura","Medio Ambiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/","url":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/","name":"El Mundo Seg\u00fan Monsanto - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s320\/elmundosegunmonsanto-portada.jpg","datePublished":"2011-05-08T02:01:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#primaryimage","url":"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s320\/elmundosegunmonsanto-portada.jpg","contentUrl":"http:\/\/2.bp.blogspot.com\/-C87MjV-zMyQ\/TcX6NlsMvcI\/AAAAAAAASuk\/rjUaVeEjgGU\/s320\/elmundosegunmonsanto-portada.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/el-mundo-segun-monsanto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"El Mundo Seg\u00fan Monsanto"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/8739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=8739"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/8739\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=8739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=8739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=8739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}