{"id":8803,"date":"2011-04-15T20:43:00","date_gmt":"2011-04-15T20:43:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2011\/04\/15\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/"},"modified":"2011-04-15T20:43:00","modified_gmt":"2011-04-15T20:43:00","slug":"imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/","title":{"rendered":"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera"},"content":{"rendered":"<div><a href=\"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s1600\/Huemula%2B2011400.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5595915552083872290\" src=\"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s400\/Huemula%2B2011400.jpg\" style=\"cursor: pointer; height: 300px; width: 400px;\" \/><\/a><\/div>\n<p> Las primeras im\u00e1genes de un huemul en la <span style=\"font-weight: bold;\">Reserva Nacional \u00d1uble<\/span>, luego de nueve a\u00f1os, fueron capturadas la semana pasada en la mencionada unidad, gracias a una c\u00e1mara trampa instalada en un sector estrat\u00e9gico en virtud de un proyecto de investigaci\u00f3n que est\u00e1n elaborando CONAF y la Pontificia Universidad Cat\u00f3lica de Chile.  El Director Regional de CONAF, Jaime Salas Arancibia, expres\u00f3 su satisfacci\u00f3n por este hallazgo, \u201c<span style=\"font-style: italic;\">ya que esto demuestra que en nuestra regi\u00f3n hay presencia de huemules; se trata de una poblaci\u00f3n peque\u00f1a, pero existe y eso es lo importante. Este testimonio gr\u00e1fico nos anima a seguir trabajando como Corporaci\u00f3n en la recuperaci\u00f3n de esta especie tan nuestra y que se encuentra en peligro de extinci\u00f3n<\/span>\u201d.  Por su parte, la encargada regional del Proyecto Huemul de CONAF, la m\u00e9dico veterinaria Ana Hinojosa S\u00e1ez, se\u00f1al\u00f3 que \u201cgracias a un trabajo investigativo que estamos realizando junto la Universidad Cat\u00f3lica, pudimos instalar una c\u00e1mara-trampa para ver el tipo de presi\u00f3n que ejercen pumas y zorros contra los huemules de la precordillera de \u00d1uble. Uno de esos dispositivos fue colocado estrat\u00e9gicamente en un sitio de conocido tr\u00e1nsito de huemules, con la esperanza de capturar una imagen de su presencia\u201d.  Es as\u00ed como dicha c\u00e1mara revel\u00f3 la secuencia de una huemul hembra que transit\u00f3 por el sector, \u201c<span style=\"font-style: italic;\">la cual tiene aspecto de un animal juvenil, lo que es esperanzador para la peque\u00f1a poblaci\u00f3n existente en la Reserva Nacional \u00d1uble y da mayores alientos para continuar el trabajo que nuestra instituci\u00f3n realiza desde hace treinta a\u00f1os para recuperar la poblaci\u00f3n de huemules<\/span>\u00ab.  En tanto que el Director Regional de CONAF precis\u00f3 que el 2002 fue la \u00faltima vez que la Corporaci\u00f3n obtuvo un registro gr\u00e1fico de la presencia de estos c\u00e9rvidos. Ese a\u00f1o, uno de los guardaparques de la Reserva Nacional \u00d1uble pudo fotografiar a una pareja de huemules. Desde ese a\u00f1o, la prospecci\u00f3n de huemules se ha realizado principalmente a trav\u00e9s de huellas y fecas y si bien se han tenido encuentros con estos maravillosos animales, estos han sido fugaces, y no dan paso a poder fotografiarlos.  <span style=\"font-weight: bold;\">El Blog de Vicente &#8211; Nat Bio B\u00edo Reconocemos Lo Nuestro<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las primeras im\u00e1genes de un huemul en la Reserva Nacional \u00d1uble, luego de nueve a\u00f1os, fueron capturadas la semana pasada en la mencionada unidad, gracias a una c\u00e1mara trampa instalada en un sector estrat\u00e9gico en virtud de un proyecto de investigaci\u00f3n que est\u00e1n elaborando CONAF y la Pontificia Universidad Cat\u00f3lica de Chile. El Director Regional [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[171,225],"tags":[],"class_list":["post-8803","post","type-post","status-publish","format-standard","hentry","category-biodiversidad","category-reservas-y-parques"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Las primeras im\u00e1genes de un huemul en la Reserva Nacional \u00d1uble, luego de nueve a\u00f1os, fueron capturadas la semana pasada en la mencionada unidad, gracias a una c\u00e1mara trampa instalada en un sector estrat\u00e9gico en virtud de un proyecto de investigaci\u00f3n que est\u00e1n elaborando CONAF y la Pontificia Universidad Cat\u00f3lica de Chile. El Director Regional [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-15T20:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s400\/Huemula%2B2011400.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera\",\"datePublished\":\"2011-04-15T20:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/\"},\"wordCount\":408,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-kjbU10UhUB0\\\/Taivi9MLCiI\\\/AAAAAAAASlQ\\\/2pLHV4fFk9E\\\/s400\\\/Huemula%2B2011400.jpg\",\"articleSection\":[\"Biodiversidad\",\"Reservas y Parques\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/\",\"name\":\"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-kjbU10UhUB0\\\/Taivi9MLCiI\\\/AAAAAAAASlQ\\\/2pLHV4fFk9E\\\/s400\\\/Huemula%2B2011400.jpg\",\"datePublished\":\"2011-04-15T20:43:00+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#primaryimage\",\"url\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-kjbU10UhUB0\\\/Taivi9MLCiI\\\/AAAAAAAASlQ\\\/2pLHV4fFk9E\\\/s400\\\/Huemula%2B2011400.jpg\",\"contentUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-kjbU10UhUB0\\\/Taivi9MLCiI\\\/AAAAAAAASlQ\\\/2pLHV4fFk9E\\\/s400\\\/Huemula%2B2011400.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/","og_locale":"es_ES","og_type":"article","og_title":"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera - Nuestro Bio B\u00edo","og_description":"Las primeras im\u00e1genes de un huemul en la Reserva Nacional \u00d1uble, luego de nueve a\u00f1os, fueron capturadas la semana pasada en la mencionada unidad, gracias a una c\u00e1mara trampa instalada en un sector estrat\u00e9gico en virtud de un proyecto de investigaci\u00f3n que est\u00e1n elaborando CONAF y la Pontificia Universidad Cat\u00f3lica de Chile. El Director Regional [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2011-04-15T20:43:00+00:00","og_image":[{"url":"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s400\/Huemula%2B2011400.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/"},"author":{"name":"","@id":""},"headline":"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera","datePublished":"2011-04-15T20:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/"},"wordCount":408,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s400\/Huemula%2B2011400.jpg","articleSection":["Biodiversidad","Reservas y Parques"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/","url":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/","name":"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s400\/Huemula%2B2011400.jpg","datePublished":"2011-04-15T20:43:00+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#primaryimage","url":"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s400\/Huemula%2B2011400.jpg","contentUrl":"http:\/\/1.bp.blogspot.com\/-kjbU10UhUB0\/Taivi9MLCiI\/AAAAAAAASlQ\/2pLHV4fFk9E\/s400\/Huemula%2B2011400.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/imagenes-de-huemul-hembra-en-la-reserva-nacional-nuble-confirman-presencia-de-cervidos-en-la-precordillera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"Im\u00e1genes De Huemul Hembra En La Reserva Nacional \u00d1uble Confirman Presencia De C\u00e9rvidos En La Precordillera"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/8803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=8803"}],"version-history":[{"count":0,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/8803\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=8803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=8803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=8803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}