{"id":8935,"date":"2011-01-22T12:32:00","date_gmt":"2011-01-22T12:32:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2011\/01\/22\/4o-festival-de-musica-clasica-verano-2010\/"},"modified":"2022-10-04T02:04:45","modified_gmt":"2022-10-04T02:04:45","slug":"4o-festival-de-musica-clasica-verano-2010","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/","title":{"rendered":"4\u00ba Festival De M\u00fasica Cl\u00e1sica &#8211; Verano 2010"},"content":{"rendered":"<div style=\"text-align: justify;\"><\/div>\n<p><a href=\"http:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s1600\/ORQUESTA%2BEN%2BCONCEPCION.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em; text-align: justify;\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5564987557972048338\" src=\"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s400\/ORQUESTA%2BEN%2BCONCEPCION.jpg\" style=\"height: 300px; width: 400px;\" \/><\/a><\/p>\n<div style=\"text-align: justify;\">Con la participaci\u00f3n de tres m\u00fasicos extranjeros invitados, la Orquesta de Curanilahue dio inicio el pasado 10 de enero a su 4\u00ba Festival de Verano. Durante dos semanas de trabajo musical, los j\u00f3venes m\u00fasicos prepararon un nuevo repertorio que se presentar\u00e1 en dos conciertos, para mostrar a la comunidad los aprendizajes adquiridos y los avances t\u00e9cnicos logrados durante el \u00faltimo a\u00f1o.<\/div>\n<p><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El concierto final se presentar\u00e1 en Curanilahue, en el marco de las actividades de celebraci\u00f3n de la Semana Curanilahuina en el Gimnasio Ol\u00edmpico de Curanilahue, el d\u00eda Domingo 23 de enero a las 20:00 horas y, al igual que el a\u00f1o pasado, se presentar\u00e1 tambi\u00e9n en Concepci\u00f3n, el d\u00eda Martes 25 de enero, a las 20:00 horas, en el Teatro de la Universidad de Concepci\u00f3n. Ambos conciertos ser\u00e1n abiertos y gratuitos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En esta oportunidad, los artistas invitados que acompa\u00f1ar\u00e1n a la orquesta son Eugenio Urrutia Borlando, pianista chileno radicado en EEUU que por segunda vez se presenta junto a la orquesta; Gabriela D\u00edaz, violinista chilena radicada en EEUU; y el cellista norteamericano, Andre Gaskins. Este a\u00f1o, la Orquesta de Curanilahue har\u00e1 homenaje a los 15 a\u00f1os de presencia de la m\u00fasica cl\u00e1sica en Curanilahue, donde m\u00e1s de 150 ni\u00f1os y j\u00f3venes han tenido la oportunidad de adquirir habilidades y aprendizajes musicales, sociales y culturales jam\u00e1s so\u00f1ados. <\/div>\n<p><a href=\"http:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/TTrOsvDkzJI\/AAAAAAAASC0\/SWwgI_WYrJ0\/s1600\/ORQUESTA%2BCURANILAHUE.jpg\" style=\"clear: right; float: right; margin-bottom: 1em; margin-left: 1em; text-align: justify;\"><img decoding=\"async\" alt=\"\" border=\"0\" id=\"BLOGGER_PHOTO_ID_5564987557510696082\" src=\"https:\/\/3.bp.blogspot.com\/_2S_RxGRVjis\/TTrOsvDkzJI\/AAAAAAAASC0\/SWwgI_WYrJ0\/s400\/ORQUESTA%2BCURANILAHUE.jpg\" style=\"height: 350px; width: 400px;\" \/><\/a><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p><\/p>\n<div style=\"text-align: justify;\">El Festival de M\u00fasica Cl\u00e1sica de Curanilahue, naci\u00f3 el 2007 como una actividad local con que la orquesta pretend\u00eda incentivar a sus alumnos a trav\u00e9s de nuevos repertorios y potenciar su desarrollo musical con un trabajo intensivo. En su tercera versi\u00f3n, se quiso mostrar este trabajo tambi\u00e9n en Concepci\u00f3n, como una forma de compartir con un p\u00fablico m\u00e1s amplio el esfuerzo del trabajo realizado y la alegr\u00eda de la m\u00fasica, experiencia que se repetir\u00e1 este a\u00f1o.  <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Los excelentes resultados alcanzados han sido posibles gracias al equipo de docentes que trabajan en la orquesta, liderados por su directora Alejandra Urrutia Borlando, quien ha trabajado de manera comprometida, buscando siempre la excelencia musical.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Durante este a\u00f1o, el Festival de M\u00fasica Cl\u00e1sica ha contado con el auspicio del Departamento de Educaci\u00f3n de Curanilahue, de la Corporaci\u00f3n Cultural Universidad de Concepci\u00f3n, que ha sido un importante apoyo con sus programas especiales para j\u00f3venes en el \u00e1mbito de la formaci\u00f3n, especialmente desde el a\u00f1o 2008, cuando se firm\u00f3 un convenio de cooperaci\u00f3n con esta instituci\u00f3n. La organizaci\u00f3n de las actividades y conciertos est\u00e1 a cargo de la coordinaci\u00f3n de la orquesta y la Direcci\u00f3n de Desarrollo Comunitario de la Ilustre Municipalidad de Curanilahue.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Este a\u00f1o el Festival contar\u00e1 tambi\u00e9n con el importante auspicio de la empresa Arauco, que desde hace m\u00e1s de 10 a\u00f1os apoya de manera ininterrumpida los distintos procesos de las orquestas que se han creado en Curanilahue. Este apoyo viene a fortalecer los lazos de esta empresa con la cultura y especialmente con la Orquesta de Curanilahue, con la que ha estado presente desde sus inicios a trav\u00e9s de la Fundaci\u00f3n Educacional Arauco.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En esta ocasi\u00f3n, el repertorio elegido para los conciertos considera la Suite de Ballet Estancia de Ginastera y el Triple Concierto para Viol\u00edn, Cello, Piano y Orquesta de Beethoven.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con la participaci\u00f3n de tres m\u00fasicos extranjeros invitados, la Orquesta de Curanilahue dio inicio el pasado 10 de enero a su 4\u00ba Festival de Verano. Durante dos semanas de trabajo musical, los j\u00f3venes m\u00fasicos prepararon un nuevo repertorio que se presentar\u00e1 en dos conciertos, para mostrar a la comunidad los aprendizajes adquiridos y los avances [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[],"class_list":["post-8935","post","type-post","status-publish","format-standard","hentry","category-musica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4\u00ba Festival De M\u00fasica Cl\u00e1sica - Verano 2010 - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4\u00ba Festival De M\u00fasica Cl\u00e1sica - Verano 2010 - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"Con la participaci\u00f3n de tres m\u00fasicos extranjeros invitados, la Orquesta de Curanilahue dio inicio el pasado 10 de enero a su 4\u00ba Festival de Verano. Durante dos semanas de trabajo musical, los j\u00f3venes m\u00fasicos prepararon un nuevo repertorio que se presentar\u00e1 en dos conciertos, para mostrar a la comunidad los aprendizajes adquiridos y los avances [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-22T12:32:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T02:04:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s400\/ORQUESTA%2BEN%2BCONCEPCION.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"4\u00ba Festival De M\u00fasica Cl\u00e1sica &#8211; Verano 2010\",\"datePublished\":\"2011-01-22T12:32:00+00:00\",\"dateModified\":\"2022-10-04T02:04:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/\"},\"wordCount\":575,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TTrOswxkedI\\\/AAAAAAAASC8\\\/zwwRJ8pXd7w\\\/s400\\\/ORQUESTA%2BEN%2BCONCEPCION.jpg\",\"articleSection\":[\"M\u00fasica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/\",\"name\":\"4\u00ba Festival De M\u00fasica Cl\u00e1sica - Verano 2010 - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TTrOswxkedI\\\/AAAAAAAASC8\\\/zwwRJ8pXd7w\\\/s400\\\/ORQUESTA%2BEN%2BCONCEPCION.jpg\",\"datePublished\":\"2011-01-22T12:32:00+00:00\",\"dateModified\":\"2022-10-04T02:04:45+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#primaryimage\",\"url\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TTrOswxkedI\\\/AAAAAAAASC8\\\/zwwRJ8pXd7w\\\/s400\\\/ORQUESTA%2BEN%2BCONCEPCION.jpg\",\"contentUrl\":\"https:\\\/\\\/4.bp.blogspot.com\\\/_2S_RxGRVjis\\\/TTrOswxkedI\\\/AAAAAAAASC8\\\/zwwRJ8pXd7w\\\/s400\\\/ORQUESTA%2BEN%2BCONCEPCION.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/4o-festival-de-musica-clasica-verano-2010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4\u00ba Festival De M\u00fasica Cl\u00e1sica &#8211; Verano 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4\u00ba Festival De M\u00fasica Cl\u00e1sica - Verano 2010 - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/","og_locale":"es_ES","og_type":"article","og_title":"4\u00ba Festival De M\u00fasica Cl\u00e1sica - Verano 2010 - Nuestro Bio B\u00edo","og_description":"Con la participaci\u00f3n de tres m\u00fasicos extranjeros invitados, la Orquesta de Curanilahue dio inicio el pasado 10 de enero a su 4\u00ba Festival de Verano. Durante dos semanas de trabajo musical, los j\u00f3venes m\u00fasicos prepararon un nuevo repertorio que se presentar\u00e1 en dos conciertos, para mostrar a la comunidad los aprendizajes adquiridos y los avances [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2011-01-22T12:32:00+00:00","article_modified_time":"2022-10-04T02:04:45+00:00","og_image":[{"url":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s400\/ORQUESTA%2BEN%2BCONCEPCION.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/"},"author":{"name":"","@id":""},"headline":"4\u00ba Festival De M\u00fasica Cl\u00e1sica &#8211; Verano 2010","datePublished":"2011-01-22T12:32:00+00:00","dateModified":"2022-10-04T02:04:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/"},"wordCount":575,"commentCount":0,"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s400\/ORQUESTA%2BEN%2BCONCEPCION.jpg","articleSection":["M\u00fasica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/","url":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/","name":"4\u00ba Festival De M\u00fasica Cl\u00e1sica - Verano 2010 - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#primaryimage"},"image":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#primaryimage"},"thumbnailUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s400\/ORQUESTA%2BEN%2BCONCEPCION.jpg","datePublished":"2011-01-22T12:32:00+00:00","dateModified":"2022-10-04T02:04:45+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#primaryimage","url":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s400\/ORQUESTA%2BEN%2BCONCEPCION.jpg","contentUrl":"https:\/\/4.bp.blogspot.com\/_2S_RxGRVjis\/TTrOswxkedI\/AAAAAAAASC8\/zwwRJ8pXd7w\/s400\/ORQUESTA%2BEN%2BCONCEPCION.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/4o-festival-de-musica-clasica-verano-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"4\u00ba Festival De M\u00fasica Cl\u00e1sica &#8211; Verano 2010"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/8935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=8935"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/8935\/revisions"}],"predecessor-version":[{"id":13781,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/8935\/revisions\/13781"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=8935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=8935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=8935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}