{"id":9091,"date":"2010-09-24T21:13:00","date_gmt":"2010-09-24T21:13:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2010\/09\/24\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/"},"modified":"2022-10-05T21:27:34","modified_gmt":"2022-10-05T21:27:34","slug":"en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/","title":{"rendered":"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales"},"content":{"rendered":"<div style=\"text-align: justify;\">El jueves 30 de septiembre, a las 11 horas, en la Universidad del Bio B\u00edo (Avda. Collao 1202, Concepci\u00f3n) se realizar\u00e1 el lanzamiento del II Encuentro Nacional de Gestores Culturales organizado por la Universidad del Bio B\u00edo y la Escuela de Gestores y Animadores Culturales (EGAC). La invitaci\u00f3n es para los gestores y animadores culturales de la Regi\u00f3n del Bio B\u00edo.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En esta jornada don Roberto Guerra Veas, Presidente de <a href=\"http:\/\/www.egac.cl\/\">EGAC<\/a>, lanzar\u00e1 para la Regi\u00f3n del Bio B\u00edo el libro-memoria del Primer Encuentro Nacional de Gestores y Animadores Culturales, iniciativa realizada en Santiago en octubre de 2009. Es la primera publicaci\u00f3n de Ediciones <a href=\"http:\/\/www.egac.cl\/\">EGAC<\/a>, en los pr\u00f3ximos meses realizar\u00e1 su segunda entrega con un texto dedicado a la Animaci\u00f3n Sociocultural. <\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Cabe se\u00f1alar que el libro se distribuir\u00e1 gratuitamente a m\u00e1s de 400 organizaciones y personas que colaboraron en las diversas fases del proceso, lo mismo que a Bibliotecas e instituciones de Chile y Latinoam\u00e9rica. Del mismo modo, quienes lo deseen, lo podr\u00e1n adquirir (costo m\u00e1s gastos de env\u00edo) solicit\u00e1ndolo al correo escuelagc@yahoo.es<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Paralelamente se dar\u00e1 a conocer el programa del Segundo Encuentro Nacional de Gestores Culturales, a realizarse en la ciudad de Concepci\u00f3n los d\u00edas 4, 5 y 6 de noviembre pr\u00f3ximo, que ya tiene confirmada la participaci\u00f3n de numerosas delegaciones que vendr\u00e1n de Ecuador, Brasil, M\u00e9xico, Colombia, Argentina, Bolivia, Espa\u00f1a, entre otros pa\u00edses de Am\u00e9rica y Europa (VER <a href=\"http:\/\/segundoencuentrodegestores.wordpress.com\/\">http:\/\/segundoencuentrodegestores.wordpress.com<\/a>).<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Tambi\u00e9n se invitar\u00e1 a los gestores culturales de la Regi\u00f3n del Bio B\u00edo a celebrar el pr\u00f3ximo 9 de octubre el D\u00eda del Gestor Cultural, instaurado el a\u00f1o 2009 durante el Primer Encuentro Nacional de Gestores y Animadores Culturales, celebraci\u00f3n a la que adhieren agrupaciones de gestores culturales como Anfocultura, Adcultura, entre otras.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 30 de septiembre, a las 11 horas, en la Universidad del Bio B\u00edo (Avda. Collao 1202, Concepci\u00f3n) se realizar\u00e1 el lanzamiento del II Encuentro Nacional de Gestores Culturales organizado por la Universidad del Bio B\u00edo y la Escuela de Gestores y Animadores Culturales (EGAC). La invitaci\u00f3n es para los gestores y animadores culturales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[196,207],"tags":[],"class_list":["post-9091","post","type-post","status-publish","format-standard","hentry","category-congresos","category-gestion-cultural"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"El jueves 30 de septiembre, a las 11 horas, en la Universidad del Bio B\u00edo (Avda. Collao 1202, Concepci\u00f3n) se realizar\u00e1 el lanzamiento del II Encuentro Nacional de Gestores Culturales organizado por la Universidad del Bio B\u00edo y la Escuela de Gestores y Animadores Culturales (EGAC). La invitaci\u00f3n es para los gestores y animadores culturales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-24T21:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T21:27:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales\",\"datePublished\":\"2010-09-24T21:13:00+00:00\",\"dateModified\":\"2022-10-05T21:27:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/\"},\"wordCount\":323,\"commentCount\":0,\"articleSection\":[\"Congresos\",\"Gesti\u00f3n Cultural\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/\",\"name\":\"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2010-09-24T21:13:00+00:00\",\"dateModified\":\"2022-10-05T21:27:34+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/","og_locale":"es_ES","og_type":"article","og_title":"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales - Nuestro Bio B\u00edo","og_description":"El jueves 30 de septiembre, a las 11 horas, en la Universidad del Bio B\u00edo (Avda. Collao 1202, Concepci\u00f3n) se realizar\u00e1 el lanzamiento del II Encuentro Nacional de Gestores Culturales organizado por la Universidad del Bio B\u00edo y la Escuela de Gestores y Animadores Culturales (EGAC). La invitaci\u00f3n es para los gestores y animadores culturales [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2010-09-24T21:13:00+00:00","article_modified_time":"2022-10-05T21:27:34+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/"},"author":{"name":"","@id":""},"headline":"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales","datePublished":"2010-09-24T21:13:00+00:00","dateModified":"2022-10-05T21:27:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/"},"wordCount":323,"commentCount":0,"articleSection":["Congresos","Gesti\u00f3n Cultural"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/","url":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/","name":"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2010-09-24T21:13:00+00:00","dateModified":"2022-10-05T21:27:34+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/en-la-ubb-sera-lanzado-el-2o-encuentro-nacional-de-gestores-culturales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"En La UBB Ser\u00e1 Lanzado El 2\u00ba Encuentro Nacional De Gestores Culturales"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/9091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=9091"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/9091\/revisions"}],"predecessor-version":[{"id":14095,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/9091\/revisions\/14095"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=9091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=9091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=9091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}