{"id":9194,"date":"2010-07-16T13:55:00","date_gmt":"2010-07-16T13:55:00","guid":{"rendered":"https:\/\/www.fraczinet.cl\/sitio\/2010\/07\/16\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/"},"modified":"2022-10-04T15:33:06","modified_gmt":"2022-10-04T15:33:06","slug":"ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2","status":"publish","type":"post","link":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/","title":{"rendered":"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d"},"content":{"rendered":"<div style=\"text-align: justify;\">\u201cSeguimos trabajando en la demanda. En realidad, nadie nos ha dado una respuesta sobre qu\u00e9 va a pasar con nosotros\u201d, sostuvo Claudio Guti\u00e9rrez, al conmemorarse ayer cuatro a\u00f1os de la fat\u00eddica tragedia fluvial que dej\u00f3 nueve v\u00edctimas fatales en toda la Provincia de Bio B\u00edo, adem\u00e1s de da\u00f1os materiales y traumas sicol\u00f3gicos en familias ribere\u00f1as. <a href=\"http:\/\/www.diariolatribuna.cl\/\">La Tribuna de Los Angeles<\/a>, 12 de julio 2010.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El 11 de julio de 2006, un fat\u00eddico temporal de viento y lluvia azot\u00f3 a gran parte de la Provincia de Bio B\u00edo, convirti\u00e9ndose en la tragedia fluvial m\u00e1s grave que se recuerde en d\u00e9cadas. De hecho, la cat\u00e1strofe dej\u00f3 un triste saldo de nueve muertos residentes en distintas localidades de la zona, adem\u00e1s de millonarios da\u00f1os materiales; todo esto con la complicidad de la sorpresiva crecida de r\u00edos y canales que devastaron terrenos agr\u00edcolas y terminaron con la vida de cientos de animales.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ayer, al cumplirse cuatro a\u00f1os de esta triste jornada, el vocero de cinco comunidades rurales directamente afectadas, Claudio Guti\u00e9rrez, asegur\u00f3 que \u201c<span style=\"font-weight: bold;\">ni el Estado ni Endesa se han hecho responsables por lo que ocurri\u00f3<\/span>\u201d.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El dirigente representa a los sectores La Suerte, El Chequ\u00e9n, La Monta\u00f1a, Mesam\u00e1vida y Duqueco Cuel, que en conjunto presentaron una millonaria demanda contra el Estado y a la empresa hidroel\u00e9ctrica, a quienes exigen reparaciones por los da\u00f1os morales y econ\u00f3micos sufridos en julio de 2006.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u201cSeguimos trabajando en la demanda\u201d, se\u00f1al\u00f3 Guti\u00e9rrez en conversaci\u00f3n con <a href=\"http:\/\/www.diariolatribuna.cl\/\">La Tribuna<\/a>. \u201cEn realidad, nadie nos ha dado una respuesta sobre qu\u00e9 va a pasar con nosotros, ni el Estado ni Endesa se han hecho responsables por lo que ocurri\u00f3. Entonces, una de las grandes deudas que todav\u00eda hay con nosotros es la reparaci\u00f3n a trav\u00e9s de la justicia\u201d.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En el marco del curso que ha seguido la demanda, vecinos de los cinco sectores afectados participaron ayer en una reuni\u00f3n con el abogado Juan Pablo Gallardo, para afinar detalles de lo que ser\u00e1 su participaci\u00f3n como testigos.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La cita fue la primera de dos sesiones que se llevar\u00e1n a cabo con dicho prop\u00f3sito, seg\u00fan manifest\u00f3 Claudio Guti\u00e9rrez.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">TRAUMA PSICOL\u00d3GICO<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Sin embargo, pese a esperar reparaciones a trav\u00e9s de la justicia, los perjuicios para las familias ribere\u00f1as han ido en aumento en el aspecto psicol\u00f3gico.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">\u201cEste es un tema que creo no vamos a subsanar. Cada a\u00f1o ha sido peor\u201d, asever\u00f3 Claudio Guti\u00e9rrez. A\u00f1adi\u00f3 que \u201cesto nos qued\u00f3 como una herida, porque cada vez que llueve estamos preocupados sobre qu\u00e9 va a pasar con el r\u00edo. Este es un tema que creo no vamos a superar nunca\u201d.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">El dirigente manifest\u00f3 que al cumplirse cuatro a\u00f1os de la tragedia fluvial existe frustraci\u00f3n en las comunidades ribere\u00f1as, por lo que espera una acci\u00f3n m\u00e1s r\u00e1pida de la justicia. Adem\u00e1s, sostuvo que es fundamental el reconocimiento por parte del Estado y de le empresa Endesa de las eventuales responsabilidades hacia las familias afectadas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">RECUERDAN A V\u00cdCTIMAS<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Con una ceremonia ecum\u00e9nica en la que esperan la presencia de diversas autoridades comunales y provinciales, los vecinos del sector La Suerte y sus alrededores recordaron a las v\u00edctimas de las inundaciones ocurridas el <span style=\"font-weight: bold;\">11 de julio de 2006<\/span>, en un memorial inaugurado el a\u00f1o pasado en el kil\u00f3metro 19 de la Ruta Q 180, camino a Nacimiento.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">En el lugar se dej\u00f3 constancia de cinco de las nueve personas fallecidas en la Provincia de Bio B\u00edo: Hern\u00e1n Jara Rebolledo, Jorge Jara Rebolledo, Esteban Javier Alveal Zuloaga, Raquel Navarrete Henr\u00edquez y Elba Lizama Lizama. Esta \u00faltima viv\u00eda en el sector Duqueco Cuel, mientras que las otras cuatro resid\u00edan en La Suerte.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><a href=\"http:\/\/www.diariolatribuna.cl\/\">Diario La Tribuna<\/a> de Los \u00c1ngeles<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSeguimos trabajando en la demanda. En realidad, nadie nos ha dado una respuesta sobre qu\u00e9 va a pasar con nosotros\u201d, sostuvo Claudio Guti\u00e9rrez, al conmemorarse ayer cuatro a\u00f1os de la fat\u00eddica tragedia fluvial que dej\u00f3 nueve v\u00edctimas fatales en toda la Provincia de Bio B\u00edo, adem\u00e1s de da\u00f1os materiales y traumas sicol\u00f3gicos en familias ribere\u00f1as. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[197],"tags":[],"class_list":["post-9194","post","type-post","status-publish","format-standard","hentry","category-provincia-de-bio-bio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d - Nuestro Bio B\u00edo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d - Nuestro Bio B\u00edo\" \/>\n<meta property=\"og:description\" content=\"\u201cSeguimos trabajando en la demanda. En realidad, nadie nos ha dado una respuesta sobre qu\u00e9 va a pasar con nosotros\u201d, sostuvo Claudio Guti\u00e9rrez, al conmemorarse ayer cuatro a\u00f1os de la fat\u00eddica tragedia fluvial que dej\u00f3 nueve v\u00edctimas fatales en toda la Provincia de Bio B\u00edo, adem\u00e1s de da\u00f1os materiales y traumas sicol\u00f3gicos en familias ribere\u00f1as. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Nuestro Bio B\u00edo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/15721414452\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-16T13:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T15:33:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"159\" \/>\n\t<meta property=\"og:image:height\" content=\"79\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:site\" content=\"@nuestrobiobio\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d\",\"datePublished\":\"2010-07-16T13:55:00+00:00\",\"dateModified\":\"2022-10-04T15:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/\"},\"wordCount\":665,\"commentCount\":0,\"articleSection\":[\"Provincia de Bio B\u00edo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/\",\"name\":\"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d - Nuestro Bio B\u00edo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\"},\"datePublished\":\"2010-07-16T13:55:00+00:00\",\"dateModified\":\"2022-10-04T15:33:06+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/\",\"name\":\"Nuestro Bio B\u00edo\",\"description\":\"Tierra de Encuentros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fraczinet.cl\\\/sitio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d - Nuestro Bio B\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d - Nuestro Bio B\u00edo","og_description":"\u201cSeguimos trabajando en la demanda. En realidad, nadie nos ha dado una respuesta sobre qu\u00e9 va a pasar con nosotros\u201d, sostuvo Claudio Guti\u00e9rrez, al conmemorarse ayer cuatro a\u00f1os de la fat\u00eddica tragedia fluvial que dej\u00f3 nueve v\u00edctimas fatales en toda la Provincia de Bio B\u00edo, adem\u00e1s de da\u00f1os materiales y traumas sicol\u00f3gicos en familias ribere\u00f1as. [&hellip;]","og_url":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/","og_site_name":"Nuestro Bio B\u00edo","article_publisher":"https:\/\/www.facebook.com\/groups\/15721414452\/","article_published_time":"2010-07-16T13:55:00+00:00","article_modified_time":"2022-10-04T15:33:06+00:00","og_image":[{"width":159,"height":79,"url":"https:\/\/www.fraczinet.cl\/sitio\/wp-content\/uploads\/2021\/07\/bannerlogo-1.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_creator":"@nuestrobiobio","twitter_site":"@nuestrobiobio","twitter_misc":{"Escrito por":"","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/#article","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/"},"author":{"name":"","@id":""},"headline":"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d","datePublished":"2010-07-16T13:55:00+00:00","dateModified":"2022-10-04T15:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/"},"wordCount":665,"commentCount":0,"articleSection":["Provincia de Bio B\u00edo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/","url":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/","name":"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d - Nuestro Bio B\u00edo","isPartOf":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/#website"},"datePublished":"2010-07-16T13:55:00+00:00","dateModified":"2022-10-04T15:33:06+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraczinet.cl\/sitio\/ni-el-estado-ni-endesa-se-han-hecho-responsables-por-lo-que-ocurrio-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fraczinet.cl\/sitio\/"},{"@type":"ListItem","position":2,"name":"\u201cNi El Estado Ni Endesa Se Han Hecho Responsables Por Lo Que Ocurri\u00f3\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.fraczinet.cl\/sitio\/#website","url":"https:\/\/www.fraczinet.cl\/sitio\/","name":"Nuestro Bio B\u00edo","description":"Tierra de Encuentros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraczinet.cl\/sitio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/9194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/comments?post=9194"}],"version-history":[{"count":1,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/9194\/revisions"}],"predecessor-version":[{"id":13874,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/posts\/9194\/revisions\/13874"}],"wp:attachment":[{"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/media?parent=9194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/categories?post=9194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraczinet.cl\/sitio\/wp-json\/wp\/v2\/tags?post=9194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}